{"id":67210,"date":"2026-09-02T10:28:37","date_gmt":"2026-09-02T13:28:37","guid":{"rendered":"https:\/\/bonettiassociados.com.br\/?p=67210"},"modified":"2026-09-02T10:28:37","modified_gmt":"2026-09-02T13:28:37","slug":"o-desafio-de-governanca-do-comite-gestor-do-ibs","status":"publish","type":"post","link":"https:\/\/bonettiassociados.com.br\/index.php\/2026\/09\/02\/o-desafio-de-governanca-do-comite-gestor-do-ibs\/","title":{"rendered":"O DESAFIO DE GOVERNAN\u00c7A DO COMIT\u00ca GESTOR DO IBS"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Sem procedimentos capazes de organizar a negocia\u00e7\u00e3o, mecanismos concebidos para proteger o equil\u00edbrio federativo podem se converter em pontos recorrentes de veto.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A cria\u00e7\u00e3o do Imposto sobre Bens e Servi\u00e7os (IBS) trouxe um desafio institucional sem paralelo no sistema tribut\u00e1rio brasileiro. Estados, Distrito Federal e mais de 5.500 munic\u00edpios passar\u00e3o a compartilhar a administra\u00e7\u00e3o de um mesmo tributo com legisla\u00e7\u00e3o uniforme. Para organizar essa coordena\u00e7\u00e3o, a Reforma Tribut\u00e1ria criou o Comit\u00ea Gestor do IBS (CGIBS), respons\u00e1vel por fun\u00e7\u00f5es centrais do novo sistema.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A inst\u00e2ncia m\u00e1xima de delibera\u00e7\u00e3o do CGIBS \u00e9 seu Conselho Superior, composto por 54 integrantes: 27 representantes dos Estados e do Distrito Federal e 27 dos munic\u00edpios. A paridade procura preservar o equil\u00edbrio federativo, mas a composi\u00e7\u00e3o de cada bloco segue crit\u00e9rios diferentes, assim como as regras utilizadas para transformar seus votos em decis\u00f5es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">No bloco estadual, uma decis\u00e3o somente \u00e9 aprovada quando re\u00fane a maioria absoluta dos representantes e votos correspondentes a mais de 50% da popula\u00e7\u00e3o brasileira. A regra combina igualdade entre os entes federativos e representatividade Leia tamb\u00e9m: Moraes e Mendon\u00e7a batem boca em reuni\u00e3o tensa sobre mensagens de populacional. Uma maioria formada por Estados que representem parcela minorit\u00e1ria da popula\u00e7\u00e3o n\u00e3o \u00e9 suficiente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A solu\u00e7\u00e3o adotada para os munic\u00edpios foi diferente. Das 27 cadeiras municipais, 14 s\u00e3o constitu\u00eddas por uma elei\u00e7\u00e3o em que cada munic\u00edpio possui o mesmo peso, enquanto as outras 13 s\u00e3o formadas por elei\u00e7\u00e3o na qual os votos s\u00e3o ponderados pela popula\u00e7\u00e3o. Os mesmos crit\u00e9rios reaparecem no bloco municipal, mas em outro momento. Entre os Estados, ambos condicionam a decis\u00e3o. Entre os munic\u00edpios, condicionam a forma\u00e7\u00e3o do Conselho.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Constitu\u00eddas as 27 cadeiras municipais, essa distin\u00e7\u00e3o desaparece. Cada representante possui um voto e as decis\u00f5es exigem maioria absoluta, equivalente a 14 votos. A popula\u00e7\u00e3o \u00e9 relevante para formar 13 cadeiras, mas n\u00e3o interfere diretamente no peso delas durante as delibera\u00e7\u00f5es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Pela regra geral, as chapas para as 14 vagas escolhidas segundo a igualdade entre munic\u00edpios s\u00e3o apresentadas pela Confedera\u00e7\u00e3o Nacional de Munic\u00edpios (CNM), enquanto as chapas para as 13 vagas submetidas \u00e0 pondera\u00e7\u00e3o populacional s\u00e3o apresentadas pela Frente Nacional de Prefeitas e Prefeitos (FNP). Havendo alinhamento entre os representantes de cada grupo, as 14 cadeiras formam, sozinhas, a maioria absoluta exigida para uma decis\u00e3o municipal. As 13 vinculadas ao crit\u00e9rio populacional precisam obter pelo menos um voto adicional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os representantes podem formar coaliz\u00f5es distintas e n\u00e3o est\u00e3o juridicamente vinculados \u00e0s entidades respons\u00e1veis pelas chapas. A regra, contudo, cria uma assimetria objetiva: um grupo coincide com a maioria necess\u00e1ria para decidir, enquanto o outro precisa formar uma coaliz\u00e3o. Se houver alinhamento recorrente, a divis\u00e3o criada para acomodar duas formas de representatividade conferir\u00e1 capacidades decis\u00f3rias diferentes a cada uma delas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A discuss\u00e3o sobre a governan\u00e7a do CGIBS antecede seu desenho atual. Estudos do Centro de Cidadania Fiscal (CCiF), com papel relevante na formula\u00e7\u00e3o t\u00e9cnica da PEC 45, propunham uma arquitetura em tr\u00eas n\u00edveis: Assembleia Geral, de composi\u00e7\u00e3o federativa ampla, Conselho de Administra\u00e7\u00e3o de nove membros e Diretoria Executiva de cinco. Representa\u00e7\u00e3o, governan\u00e7a e execu\u00e7\u00e3o ocupavam inst\u00e2ncias distintas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ao Conselho de Administra\u00e7\u00e3o caberiam fun\u00e7\u00f5es como aprovar a regulamenta\u00e7\u00e3o infralegal do IBS, definir a estrutura gerencial, indicar a Diretoria Executiva e aprovar o regimento interno. Entre o grande colegiado representativo e a estrutura operacional haveria uma inst\u00e2ncia reduzida de governan\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A estrutura aprovada seguiu outro caminho. A Lei Complementar n\u00ba 227, de 2026, definiu o Conselho Superior de 54 membros como inst\u00e2ncia m\u00e1xima de delibera\u00e7\u00e3o do CGIBS. O Conselho aprova o regulamento \u00fanico do IBS, o regimento interno, atos para uniformizar a interpreta\u00e7\u00e3o da legisla\u00e7\u00e3o, propostas normativas conjuntas com a Uni\u00e3o e planos da Diretoria Executiva. Tamb\u00e9m pode avocar compet\u00eancias da Diretoria e rever suas decis\u00f5es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Essa concentra\u00e7\u00e3o de compet\u00eancias aumenta a import\u00e2ncia dos procedimentos que antecedem a vota\u00e7\u00e3o. Um colegiado de 54 membros, formado por interesses federativos heterog\u00eaneos e submetido a regras exigentes de aprova\u00e7\u00e3o, precisa de mecanismos capazes de organizar suas decis\u00f5es. Agenda, instru\u00e7\u00e3o t\u00e9cnica, relatoria, processamento de emendas e constru\u00e7\u00e3o de consensos passam a determinar a capacidade decis\u00f3ria do Comit\u00ea. A qualidade desses procedimentos ser\u00e1 decisiva para que diverg\u00eancias leg\u00edtimas n\u00e3o se convertam em paralisia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Conselho Superior re\u00fane duas esferas federativas e entes com dimens\u00f5es e interesses distintos. Suas delibera\u00e7\u00f5es dependem da forma\u00e7\u00e3o simult\u00e2nea das maiorias estadual e municipal. As salvaguardas contra a concentra\u00e7\u00e3o de poder ampliam a quantidade de interesses que precisam ser conciliados. Sem procedimentos capazes de organizar essa negocia\u00e7\u00e3o, mecanismos concebidos para proteger o equil\u00edbrio federativo podem se converter em pontos recorrentes de veto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Representatividade e capacidade decis\u00f3ria s\u00e3o dimens\u00f5es da mesma arquitetura institucional. O desenho do CGIBS dedicou aten\u00e7\u00e3o \u00e0 primeira, criando regras para acomodar Estados e munic\u00edpios de diferentes tamanhos. A segunda recebeu solu\u00e7\u00e3o menos elaborada. Um Conselho de 54 membros concentra compet\u00eancias relevantes e decide sob regras que multiplicam as maiorias necess\u00e1rias, enquanto parte dos crit\u00e9rios de representatividade desaparece no momento da delibera\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O CGIBS foi criado para resolver um problema de coordena\u00e7\u00e3o. O IBS substitui a administra\u00e7\u00e3o fragmentada de tributos estaduais e municipais por uma estrutura compartilhada, que exigir\u00e1 decis\u00f5es frequentes sobre regulamenta\u00e7\u00e3o, interpreta\u00e7\u00e3o, arrecada\u00e7\u00e3o, fiscaliza\u00e7\u00e3o e distribui\u00e7\u00e3o de receitas. Se sua governan\u00e7a transformar diverg\u00eancias federativas em bloqueios recorrentes, parte do problema que a Reforma procurou superar reaparecer\u00e1 dentro da institui\u00e7\u00e3o criada para solucion\u00e1-lo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A implementa\u00e7\u00e3o do IBS colocar\u00e1 \u00e0 prova a pr\u00f3pria arquitetura institucional criada para administr\u00e1-lo. O CGIBS ter\u00e1 de conciliar a diversidade de interesses de uma federa\u00e7\u00e3o complexa com a necessidade cotidiana de produzir decis\u00f5es. Se o desenho criado para garantir representatividade dificultar sistematicamente a forma\u00e7\u00e3o dessas decis\u00f5es, o problema deixar\u00e1 de ser operacional e passar\u00e1 a ser institucional. A legitimidade do Comit\u00ea depender\u00e1 de representar adequadamente Estados e munic\u00edpios. Sua efetividade depender\u00e1 de uma condi\u00e7\u00e3o ainda mais b\u00e1sica: ser capaz de decidir.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: VALOR ECON\u00d4MICO &#8211; POR ERNESTO GUEDES E M\u00c1RIO WESTRUP<\/strong><\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sem procedimentos capazes de organizar a negocia\u00e7\u00e3o, mecanismos concebidos para [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[9],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-hu2","_links":{"self":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67210"}],"collection":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67210"}],"version-history":[{"count":1,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67210\/revisions"}],"predecessor-version":[{"id":67211,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67210\/revisions\/67211"}],"wp:attachment":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}