{"id":62896,"date":"2026-05-13T10:18:52","date_gmt":"2026-05-13T13:18:52","guid":{"rendered":"https:\/\/bonettiassociados.com.br\/?p=62896"},"modified":"2026-05-13T10:18:52","modified_gmt":"2026-05-13T13:18:52","slug":"carf-mantem-cobranca-de-iof-e-pis-cofins-por-simulacao-envolvendo-seguradora","status":"publish","type":"post","link":"https:\/\/bonettiassociados.com.br\/index.php\/2026\/05\/13\/carf-mantem-cobranca-de-iof-e-pis-cofins-por-simulacao-envolvendo-seguradora\/","title":{"rendered":"CARF MANT\u00c9M COBRAN\u00c7A DE IOF E PIS\/COFINS POR SIMULA\u00c7\u00c3O ENVOLVENDO SEGURADORA"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Conselho valida IOF, PIS e Cofins por suposto aproveitamento indevido de isen\u00e7\u00e3o tribut\u00e1ria em 2015 e em 2016.<\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A 2\u00aa Turma da 2\u00aa C\u00e2mara da 3\u00aa Se\u00e7\u00e3o do Conselho Administrativo de Recursos Fiscais (<strong>Carf<\/strong>) manteve cobran\u00e7as de\u00a0<strong>IOF<\/strong>,\u00a0<strong>PIS<\/strong>\u00a0e\u00a0<strong>Cofins<\/strong>\u00a0contra a Regulamentar Sinistros Ltda por suposta simula\u00e7\u00e3o por meio do uso de uma associa\u00e7\u00e3o para o aproveitamento de isen\u00e7\u00e3o tribut\u00e1ria nos anos de 2015 e 2016. O resultado foi proferido por unanimidade.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O processo envolveu a rela\u00e7\u00e3o entre a Regulamentar Sinistros e a Associa\u00e7\u00e3o dos Amigos de Santa Catarina (Aasc), entidade sem fins lucrativos que oferece prote\u00e7\u00e3o veicular a seus associados. Durante uma fiscaliza\u00e7\u00e3o da Aasc, a Receita Federal concluiu que as mensalidades cobradas pela associa\u00e7\u00e3o n\u00e3o eram rateio de despesas, mas pr\u00eamio de seguro, e responsabilizou a Regulamentar pelos fatos e opera\u00e7\u00f5es. De acordo com o fisco, os s\u00f3cios da Regulamentar ocupavam cargos de dire\u00e7\u00e3o na Aasc.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A defesa da contribuinte argumentou que a Aasc n\u00e3o oferece o servi\u00e7o de seguros, mas prote\u00e7\u00e3o patrimonial mutualista para, principalmente, propriet\u00e1rios de ve\u00edculos antigos que n\u00e3o s\u00e3o aceitos por seguradoras. Tamb\u00e9m afirmou que a Regulamentar apenas prestou servi\u00e7os para a associa\u00e7\u00e3o e por isso n\u00e3o deveria ser parte do processo. O mais adequado, sustentou, seria cassar a isen\u00e7\u00e3o da Aasc e cobrar dela os tributos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O relator, conselheiro Rodrigo Lorenzon Yunan Gassibe, votou para manter as cobran\u00e7as. O julgador entendeu que a Aasc n\u00e3o pode ser classificada como grupo restrito de ajuda m\u00fatua porque seus servi\u00e7os s\u00e3o ofertados de forma abrangente. Para ele, ficou provado que a atividade da associa\u00e7\u00e3o seria a comercializa\u00e7\u00e3o de planos de seguros e, consequentemente, as mensalidades cobradas por ela teriam natureza de pr\u00eamio. Al\u00e9m disso, estaria claro que as decis\u00f5es gerenciais da entidade \u201ccaminhavam conforme a vontade dos s\u00f3cios da Regulamentar\u201d. Gassibe foi acompanhado pelos demais conselheiros.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os processos tramitam com os n\u00fameros 11516.722682\/2018-59 e 11516.722684\/2018-48.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: JOTA \u2013 POR MATEUS MELLO<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><u>\u00a0<\/u><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conselho valida IOF, PIS e Cofins por suposto aproveitamento indevido [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-gms","_links":{"self":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62896"}],"collection":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62896"}],"version-history":[{"count":1,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62896\/revisions"}],"predecessor-version":[{"id":62897,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62896\/revisions\/62897"}],"wp:attachment":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}