{"id":62678,"date":"2026-05-07T10:05:46","date_gmt":"2026-05-07T13:05:46","guid":{"rendered":"https:\/\/bonettiassociados.com.br\/?p=62678"},"modified":"2026-05-07T10:05:46","modified_gmt":"2026-05-07T13:05:46","slug":"diretriz-orcamentaria-do-governo-determina-como-sera-estimada-arrecadacao-com-cbs-e-is-em-2027","status":"publish","type":"post","link":"https:\/\/bonettiassociados.com.br\/index.php\/2026\/05\/07\/diretriz-orcamentaria-do-governo-determina-como-sera-estimada-arrecadacao-com-cbs-e-is-em-2027\/","title":{"rendered":"DIRETRIZ OR\u00c7AMENT\u00c1RIA DO GOVERNO DETERMINA COMO SER\u00c1 ESTIMADA ARRECADA\u00c7\u00c3O COM CBS E IS EM 2027"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O\u00a0<strong>PLDO (Projeto da Lei de Diretrizes Or\u00e7ament\u00e1rias)\u00a0<\/strong>enviado ao Congresso em 15 de abril reconhece as indefini\u00e7\u00f5es de al\u00edquotas de CBS (Contribui\u00e7\u00e3o sobre Bens e Servi\u00e7os) e IS (Imposto Seletivo) nas proje\u00e7\u00f5es de arrecada\u00e7\u00e3o para o ano que vem.<\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O texto determina que o governo fa\u00e7a as estimativas com base nos dados hist\u00f3ricos de arrecada\u00e7\u00e3o de:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">PIS (Programa de Integra\u00e7\u00e3o Social)<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Cofins (Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social)<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">IOF (Imposto sobre Opera\u00e7\u00f5es Financeiras) Seguros<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">IPI (Imposto sobre Produtos Industrializados)<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><em>\u201cEm que se pese o fato de que em 2027 come\u00e7ar\u00e1 a vigorar a reforma tribut\u00e1ria dos tributos indiretos da Uni\u00e3o \u2013CBS e Imposto Seletivo, em raz\u00e3o de algumas das defini\u00e7\u00f5es ainda estarem pendentes, as bases de arrecada\u00e7\u00e3o projetadas foram as mesmas dos tributos que ser\u00e3o substitu\u00eddos\u2013 PIS, Cofins, IOF Seguros e IPI\u201d, diz o documento.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Projeto de Lei de Diretrizes Or\u00e7ament\u00e1rias \u00e9 a proposta do governo que define as metas e prioridades para orientar a elabora\u00e7\u00e3o do or\u00e7amento p\u00fablico do ano seguinte.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os novos tributos pouco s\u00e3o comentados durante o resto do texto. Por\u00e9m, o PLDO come\u00e7ou a mostrar quadros das expectativas de gastos tribut\u00e1rios com a CBS e o IS. No momento, todas as estimativas est\u00e3o zeradas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A men\u00e7\u00e3o aos tributos mostra que a reforma come\u00e7a a movimentar a agenda de quem elabora as contas p\u00fablicas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O\u00a0<strong>Portal da Reforma Tribut\u00e1ria\u00a0<\/strong>j\u00e1\u00a0<strong>havia antecipado que a indefini\u00e7\u00e3o das al\u00edquotas de CBS e IS trariam ressalvas\u00a0<\/strong>da equipe econ\u00f4mica. O Minist\u00e9rio da Fazenda precisa enviar as estimativas de CBS para o TCU (Tribunal de Contas da Uni\u00e3o) at\u00e9 31 de julho. A corte de contas pode ajustar os valores at\u00e9 o fim do ano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">S\u00f3 que a prov\u00e1vel\u00a0<strong>demora para vota\u00e7\u00e3o do projeto de lei do Imposto Seletivo<\/strong>\u00a0\u2013que ainda nem foi enviado\u2013 no Congresso deve afetar os c\u00e1lculos. Quanto maiores forem os percentuais de IS, menor a CBS (e vice-versa). Isso porque o aumento da carga do Imposto Seletivo sobre alguns produtos compensa a perda de arrecada\u00e7\u00e3o com uma contribui\u00e7\u00e3o mais branda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O<strong>\u00a0Portal\u00a0<\/strong>explica abaixo a diferen\u00e7a entre:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>CBS\u00a0\u2013 <\/strong>Novo tributo que substituir\u00e1 o PIS (Programa de Integra\u00e7\u00e3o Social) e Cofins (Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social), al\u00e9m do IPI (Imposto sobre Produtos Industrializados).<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>IS\u00a0\u2013 <\/strong>Imposto sobre produtos considerados danosos \u00e0 sa\u00fade e ao meio ambiente, como cigarros e bebidas alco\u00f3licas.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: PORTAL DA REFORMA TRIBUT\u00c1RIA &#8211; POR\u00a0GABRIEL BENEVIDES &#8211; DE BRAS\u00cdLIA<\/strong><\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00a0PLDO (Projeto da Lei de Diretrizes Or\u00e7ament\u00e1rias)\u00a0enviado ao Congresso em [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[9],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-giW","_links":{"self":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62678"}],"collection":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62678"}],"version-history":[{"count":1,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62678\/revisions"}],"predecessor-version":[{"id":62679,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62678\/revisions\/62679"}],"wp:attachment":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}