{"id":55830,"date":"2025-10-06T10:55:12","date_gmt":"2025-10-06T13:55:12","guid":{"rendered":"https:\/\/bonettiassociados.com.br\/?p=55830"},"modified":"2025-10-06T11:05:56","modified_gmt":"2025-10-06T14:05:56","slug":"empresas-vencem-disputa-sobre-adicional-do-icms","status":"publish","type":"post","link":"https:\/\/bonettiassociados.com.br\/index.php\/2025\/10\/06\/empresas-vencem-disputa-sobre-adicional-do-icms\/","title":{"rendered":"EMPRESAS VENCEM DISPUTA SOBRE ADICIONAL DO ICMS"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Dezenove decis\u00f5es de quatro tribunais federais foram proferidas a favor dos contribuintes.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A maioria dos tribunais regionais federais (TRFs) do pa\u00eds j\u00e1 decidiu pela exclus\u00e3o do adicional de ICMS destinado a fundos estaduais de combate e erradica\u00e7\u00e3o da pobreza da base de c\u00e1lculo do PIS e da Cofins. Conforme levantamento realizado, todas as 19 decis\u00f5es colegiadas sobre o assunto encontradas em quatro TRFs, da 2\u00aa, 3\u00aa, 4\u00aa e 5\u00aa Regi\u00f5es, foram proferidas a favor do contribuinte.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os fundos de combate \u00e0 pobreza correspondem, na pr\u00e1tica, a um adicional de at\u00e9 2% do ICMS. Eles foram institu\u00eddos por Estados com base em previs\u00e3o do Ato das Disposi\u00e7\u00f5es Constitucionais Transit\u00f3rias (ADCT).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O tema \u00e9 considerado, pelos advogados, uma sequ\u00eancia da exclus\u00e3o do ICMS da base do PIS e da Cofins &#8211; a chamada \u201ctese do s\u00e9culo\u201d. Para as empresas, deveria ser aplicado o mesmo entendimento adotado pelo Supremo Tribunal Federal (STF). Mas, em 2024, a Receita Federal diferenciou o tributo do adicional, por meio da Solu\u00e7\u00e3o de Consulta n\u00ba 61, editada pela Coordena\u00e7\u00e3o-Geral de Tributa\u00e7\u00e3o (Cosit).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Na solu\u00e7\u00e3o de consulta, a Receita estabelece que o adicional de ICMS destinado ao Fundo de Combate \u00e0 Pobreza n\u00e3o deve ser exclu\u00eddo do PIS e da Cofins. Para o \u00f3rg\u00e3o, o adicional n\u00e3o teria a mesma natureza jur\u00eddica do ICMS e, portanto, n\u00e3o poderia ser aplicado ao caso a \u201ctese do s\u00e9culo\u201d. O \u00f3rg\u00e3o aponta, no texto, que esse ICMS tem efeito \u201ccascata\u201d, por ser cumulativo, al\u00e9m de possuir vincula\u00e7\u00e3o espec\u00edfica e n\u00e3o precisar ser repartido com os munic\u00edpios.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Judici\u00e1rio, contudo, tem recha\u00e7ado essa interpreta\u00e7\u00e3o, reconhecendo que os valores s\u00e3o de um adicional do ICMS e t\u00eam a natureza do pr\u00f3prio imposto. Os julgamentos consideram a decis\u00e3o da \u201ctese do s\u00e9culo\u201d, segundo destaca T\u00falio Parente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">At\u00e9 o momento, aponta o levantamento, n\u00e3o se tem registro de julgamento dos demais tribunais sobre o tema (TRF-1 e TRF-6). No TRF-2 (Rio de Janeiro e Esp\u00edrito Santo) foram localizados seis ac\u00f3rd\u00e3os, no TRF-3 (S\u00e3o Paulo e Mato Grosso do Sul) foram sete, no TRF-4 (Paran\u00e1, Santa Catarina e Rio Grande do Sul), dois e no TRF-5 (Alagoas, Cear\u00e1, Para\u00edba, Pernambuco, Rio Grande do Norte e Sergipe), quatro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em um dos julgados, a 4\u00aa Turma do TRF-2 considerou que a natureza do adicional \u00e9 \u201cindiscern\u00edvel da tribut\u00e1ria\u201d, o que lhe imp\u00f5e o mesmo tratamento jur\u00eddico dado ao cr\u00e9dito tribut\u00e1rio regular do imposto estadual. \u201c\u00c9 imediata e autom\u00e1tica a incid\u00eancia, sobre a esp\u00e9cie, da tese consagrada pelo STF no Tema 69, para reconhecer que os pagamentos efetuados pelo sujeito passivo a esse fundo n\u00e3o integram a receita bruta da demandante e, logo, n\u00e3o podem integrar a base de c\u00e1lculo do PIS e da Cofins\u201d (processo n\u00ba 5064653-14.2024.4.02.5101).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">No TRF-3, a 4\u00aa Turma tamb\u00e9m aplicou a decis\u00e3o do STF, seguindo inclusive a modula\u00e7\u00e3o estabelecida pelo Supremo. O caso havia sido ajuizado em 14 de junho de 2019, portanto, os valores a serem compensados ficam restringidos a cobran\u00e7as referentes a fatos ocorridos depois de mar\u00e7o de 2017 (processo n\u00ba 5010747-68.2019.4.03.6100).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cO adicional \u00e9 sem nenhuma d\u00favida ICMS. Tem todas as suas caracter\u00edsticas\u201d \u2014 Marcio Alabarce<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Decis\u00e3o no TRF-5, da 3\u00aa Turma, considerou a similaridade com outras modalidades de ICMS, como o arrecadado sobre o diferencial de al\u00edquotas (ICMS-Difal), que s\u00f3 transita pela contabilidade da empresa at\u00e9 ser recolhido ao Estado. \u201cO ICMS de tal modalidade n\u00e3o pode ser entendido como faturamento e, consequentemente, n\u00e3o deve servir \u00a0de base de c\u00e1lculo para o PIS e a Cofins\u201d, conclui no voto o relator, desembargador federal Alexandre Luna Freire (processo n\u00ba 0805339-35.2024.4.05.8100).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Segundo Parente, esse \u00e9 mais um epis\u00f3dio em que a Receita Federal busca restringir o alcance da \u201ctese do s\u00e9culo\u201d, mas encontra resist\u00eancia nos tribunais. Na pr\u00e1tica, enquanto n\u00e3o h\u00e1 judicializa\u00e7\u00e3o, afirma o advogado, as empresas s\u00e3o obrigadas a seguir a orienta\u00e7\u00e3o do \u00f3rg\u00e3o, sob pena de autua\u00e7\u00e3o, o que pode gerar passivos relevantes, acrescidos de multa e juros. \u201cTem-se, assim, um aumento indevido da carga tribut\u00e1ria, que pressiona resultados e margens de lucro, sobretudo em setores com baixa elasticidade de pre\u00e7os\u201d, diz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O advogado Aur\u00e9lio Longo Guerzoni, pondera que, diferentemente da tese da exclus\u00e3o do ICMS da base de c\u00e1lculo do PIS e da Cofins e das \u201cteses filhotes\u201d, o n\u00famero de a\u00e7\u00f5es judiciais que discutem a inclus\u00e3o do adicional de ICMS nas bases das contribui\u00e7\u00f5es \u00e9 expressivamente menor. Isso porque o adicional de ICMS destinado aos Fundos de Combate \u00e0 Pobreza deve incidir sobre produtos sup\u00e9rfluos e, em muitos casos, nas opera\u00e7\u00f5es ao consumidor final.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Guerzoni afirma que existem algumas manifesta\u00e7\u00f5es pontuais desfavor\u00e1veis aos contribuintes, em especial em decis\u00f5es monocr\u00e1ticas provis\u00f3rias que rejeitam pedidos de urg\u00eancia. Em um dos casos, o desembargador federal Jos\u00e9 Amilcar de Queiroz Machado, da 7\u00aa Turma do TRF-1, aponta que a \u201ctese do s\u00e9culo\u201d se refere ao ICMS propriamente dito, n\u00e3o se aplicando, de forma autom\u00e1tica, a outras esp\u00e9cies tribut\u00e1rias ou adicionais (processo n\u00ba 1.039209-51.2024.4.01.0000)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cApesar disso, os tribunais regionais federais t\u00eam consistentemente reconhecido a impossibilidade de inclus\u00e3o do adicional de ICMS nas bases de c\u00e1lculo do PIS e da Cofins, aplicando o mesmo racional da tese do s\u00e9culo\u201d, diz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Segundo o advogado Marcio Alabarce, o adicional \u00e9 \u201csem nenhuma d\u00favida\u201d ICMS. \u201cTem todas as suas caracter\u00edsticas, apenas uma destina\u00e7\u00e3o espec\u00edfica, e \u00e9 s\u00f3. A Fazenda tem criado distin\u00e7\u00f5es que inexistem\u201d, afirma. Para o advogado, \u00e9 uma estrat\u00e9gia de conten\u00e7\u00e3o de danos para maximizar tanto quanto poss\u00edvel a arrecada\u00e7\u00e3o fiscal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em nota, a Procuradoria-Geral da Fazenda Nacional informa que est\u00e1 acompanhando os casos e ir\u00e1 recorrer das decis\u00f5es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: VALOR ECON\u00d4MICO \u2013 POR BEATRIZ OLIVON \u2014 DE BRAS\u00cdLIA<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dezenove decis\u00f5es de quatro tribunais federais foram proferidas a favor [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-ewu","_links":{"self":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55830"}],"collection":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=55830"}],"version-history":[{"count":2,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55830\/revisions"}],"predecessor-version":[{"id":55842,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55830\/revisions\/55842"}],"wp:attachment":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=55830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=55830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=55830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}