{"id":5104,"date":"2019-10-24T09:37:22","date_gmt":"2019-10-24T12:37:22","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=5104"},"modified":"2019-10-24T09:37:22","modified_gmt":"2019-10-24T12:37:22","slug":"poderes-a-mais-mp-da-transacao-fiscal-autoriza-governo-a-pedir-falencia-de-empresas-em-recuperacao","status":"publish","type":"post","link":"https:\/\/bonettiassociados.com.br\/index.php\/2019\/10\/24\/poderes-a-mais-mp-da-transacao-fiscal-autoriza-governo-a-pedir-falencia-de-empresas-em-recuperacao\/","title":{"rendered":"PODERES A MAIS &#8211; MP DA TRANSA\u00c7\u00c3O FISCAL AUTORIZA GOVERNO A PEDIR FAL\u00caNCIA DE EMPRESAS EM RECUPERA\u00c7\u00c3O"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Se transformada em lei do jeito que est\u00e1, a Medida Provis\u00f3ria 899\/2019, que criou a transa\u00e7\u00e3o em mat\u00e9ria tribut\u00e1ria, a tal \u201cMP do contribuinte legal\u201d, tem encontro marcado com os tribunais. O inciso II do artigo 8\u00ba da MP autoriza a Fazenda a pedir a transforma\u00e7\u00e3o da recupera\u00e7\u00e3o judicial de empresas em fal\u00eancia, caso elas rescindam o acordo de transa\u00e7\u00e3o. Portanto, al\u00e9m de tratar de mat\u00e9ria de processo civil, o que \u00e9 proibido pelo artigo 62, par\u00e1grafo 1\u00ba, da Constitui\u00e7\u00e3o, a MP confronta a jurisprud\u00eancia j\u00e1 antiga do Superior Tribunal de Justi\u00e7a.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">H\u00e1 pelo menos 16 anos, o STJ entende, de forma un\u00e2nime, que a Fazenda n\u00e3o pode fazer isso, por n\u00e3o poder figurar como interessada no processo falimentar. O entendimento do STJ \u00e9 que a Fazenda tem o instrumento da execu\u00e7\u00e3o fiscal para cobrar seus cr\u00e9ditos, e n\u00e3o precisa negociar como um credor \u201cnormal\u201d com empresas em recupera\u00e7\u00e3o. O entendimento foi firmado no Recurso Especial 164.389, julgado em agosto de 2003, e no REsp 287.824, julgado em outubro de 2005.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A exposi\u00e7\u00e3o de motivos da MP n\u00e3o fala no assunto. Apenas diz que ela foi editada para regulamentar o artigo 171 do C\u00f3digo Tribut\u00e1rio Nacional, que permite acordos em mat\u00e9ria fiscal. E diz que servir\u00e1 para desafogar o contencioso tribut\u00e1rio. Apenas no Conselho Administrativo de Recursos Fiscais (Carf), diz o governo, h\u00e1 R$ 600 bilh\u00f5es em discuss\u00e3o em 120 mil processos. Na Justi\u00e7a Federal, s\u00e3o R$ 42 bilh\u00f5es em discuss\u00e3o, diz a exposi\u00e7\u00e3o de motivos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os argumentos contra a MP foram levantados pelo tributarista Felipe Contrera Novaes e levados ao professor Ives Gandra da Silva Martins Filho. A partir deles, o Conselho Superior de Direito da Federa\u00e7\u00e3o do Com\u00e9rcio de S\u00e3o Paulo (Fecom\u00e9rcio-SP) decidiu propor uma emenda \u00e0 MP, por orienta\u00e7\u00e3o do professor Ives Gandra da Silva Martins.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A proposta da Fecom\u00e9rcio \u00e9 que o artigo 8\u00ba diga, simplesmente, que o contribuinte que rescindir o acordo de transa\u00e7\u00e3o perder\u00e1 todos os seus benef\u00edcios. A ideia foi levada ao senador Alessandro Vieira (Cidadania-SE). O prazo para propor emendas \u00e0 MP termina nesta quarta-feira (23\/10).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Conjur &#8211; Por Pedro Can\u00e1rio<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se transformada em lei do jeito que est\u00e1, a Medida [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1kk","_links":{"self":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5104"}],"collection":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5104"}],"version-history":[{"count":1,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5104\/revisions"}],"predecessor-version":[{"id":5105,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5104\/revisions\/5105"}],"wp:attachment":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}