{"id":4844,"date":"2019-10-09T11:38:42","date_gmt":"2019-10-09T14:38:42","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=4844"},"modified":"2019-10-09T11:41:15","modified_gmt":"2019-10-09T14:41:15","slug":"ir-comissao-da-camara-permite-incluir-idoso-amparado-como-dependente","status":"publish","type":"post","link":"https:\/\/bonettiassociados.com.br\/index.php\/2019\/10\/09\/ir-comissao-da-camara-permite-incluir-idoso-amparado-como-dependente\/","title":{"rendered":"IR: COMISS\u00c3O DA C\u00c2MARA PERMITE INCLUIR IDOSO AMPARADO COMO DEPENDENTE"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A Comiss\u00e3o de Defesa dos Direitos da Pessoa Idosa da C\u00e2mara dos Deputados aprovou na \u00faltima sexta-feira, 4, o Projeto de Lei 498\/19, que permite ao contribuinte incluir como dependente no Imposto de Renda (IR) pessoa idosa que n\u00e3o tenha rendimentos mensais superiores ao limite de isen\u00e7\u00e3o (R$ 1.903,98).<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O projeto altera a Lei 9.250, de 26 de dezembro de 1995, que trata da Legisla\u00e7\u00e3o do Imposto de Renda. O autor da proposta, deputado Fernando Rodolfo explica que o objetivo \u00e9 criar incentivos na legisla\u00e7\u00e3o para que fam\u00edlias e pessoas com condi\u00e7\u00f5es econ\u00f4micas e financeiras possam abrigar idosos desamparados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Como bem afirma o autor, a legisla\u00e7\u00e3o brasileira imp\u00f5e \u00e0 fam\u00edlia, \u00e0 sociedade, \u00e0 comunidade, e ao poder p\u00fablico, obriga\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 pessoa idosa. Decorre que muitas vezes, o Estado carece de recursos materiais e humanos para cumprir a sua parte, n\u00e3o sendo suficiente o pagamento ao idoso de benef\u00edcio assistencial se ele n\u00e3o possui moradia, quem lhe assista para aliment\u00e1-lo e cuidar da sua sa\u00fade e outros aspectos fundamentais do chamado direito \u00e0 vida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201c\u00c9 urgente que o poder p\u00fablico ofere\u00e7a aos que amparam idosos necessitados dedu\u00e7\u00f5es fiscais por meio do IRPF. Esse idoso figurar\u00e1 como dependente do contribuinte. Isto \u00e9 justo, \u00e9tico, jur\u00eddico e constitucional, eis que o particular est\u00e1 assumindo, por inteiro, uma responsabilidade do Estado\u201d, disse o autor.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O relator da proposta na Comiss\u00e3o de Defesa dos Direitos da Pessoa Idosa, Eduardo Barbosa, aprovou o texto, mas restringiu apenas para os casos que os casos em que o acolhimento ao idoso tenha sido formalizado por meio de procedimento semelhante ao da guarda judicial prevista para as crian\u00e7as e adolescentes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><u>Tramita\u00e7\u00e3o<\/u><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O projeto ser\u00e1 analisado conclusivamente pelas comiss\u00f5es de Finan\u00e7as e Tributa\u00e7\u00e3o; e Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Fonte: CONT\u00c1BEIS \u2013 Danielle Nader<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Defesa dos Direitos da Pessoa Idosa da [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1g8","_links":{"self":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4844"}],"collection":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4844"}],"version-history":[{"count":1,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4844\/revisions"}],"predecessor-version":[{"id":4845,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4844\/revisions\/4845"}],"wp:attachment":[{"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}