{"id":7691,"date":"2020-03-25T11:05:24","date_gmt":"2020-03-25T14:05:24","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=7691"},"modified":"2020-03-25T11:05:24","modified_gmt":"2020-03-25T14:05:24","slug":"direto-do-carf-iof-credito-sobre-fluxos-financeiros-derivados-de-contratos-de-conta-corrente","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2020\/03\/25\/direto-do-carf-iof-credito-sobre-fluxos-financeiros-derivados-de-contratos-de-conta-corrente\/","title":{"rendered":"DIRETO DO CARF &#8211; &#8220;IOF-CR\u00c9DITO&#8221; SOBRE FLUXOS FINANCEIROS DERIVADOS DE CONTRATOS DE CONTA CORRENTE"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A incid\u00eancia de Imposto sobre Opera\u00e7\u00f5es de Cr\u00e9dito, C\u00e2mbio e Seguro, ou relativas a T\u00edtulos ou Valores Mobili\u00e1rios (IOF) sobre fluxos financeiros provenientes de contratos de conta corrente \u00e9 objeto de relevantes e, digam-se, contumazes debates perante as Turmas Ordin\u00e1rias do CARF, dos quais deflu\u00edram recentes manifesta\u00e7\u00f5es veiculadas em ac\u00f3rd\u00e3os proferidos pela 3\u00aa Turma da CSRF.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para compreens\u00e3o da discuss\u00e3o, esclarece-se que a controv\u00e9rsia reside, em rigor, na aplica\u00e7\u00e3o de regras de hermen\u00eautica com rela\u00e7\u00e3o ao art. 13 da lei n. 9779\/991. Quer dizer, notam-se diverg\u00eancias de interpreta\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0 defini\u00e7\u00e3o, conte\u00fado e alcance dos institutos, conceitos e formas de Direito Privado subjacentes ao assunto2, capazes de atrair ou afastar a incid\u00eancia do referido art. 13 da lei n. 9779\/99, na disponibiliza\u00e7\u00e3o de recursos financeiros escorada em contratos de conta corrente. Tais diverg\u00eancias adv\u00eam da reda\u00e7\u00e3o conferida ao art. 13 da lei n. 9779\/99, verbis:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Art. 13. As opera\u00e7\u00f5es de cr\u00e9dito correspondentes a m\u00fatuo de recursos financeiros entre pessoas jur\u00eddicas ou entre pessoa jur\u00eddica e pessoa f\u00edsica sujeitam-se \u00e0 incid\u00eancia do IOF segundo as mesmas normas aplic\u00e1veis \u00e0s opera\u00e7\u00f5es de financiamento e empr\u00e9stimos praticadas pelas institui\u00e7\u00f5es financeiras. (grifos nosso)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">De fato, a hip\u00f3tese de incid\u00eancia delineada pela norma alhures reproduzida det\u00e9m como antecedente normativo a ocorr\u00eancia de opera\u00e7\u00f5es de cr\u00e9dito correspondentes aos contratos de m\u00fatuo (o qual possui regime jur\u00eddico pr\u00f3prio, nos artigos 586 a 592 do C\u00f3digo Civil). Da\u00ed resulta a indispensabilidade da defini\u00e7\u00e3o do alcance das normas de Direito Privado em \u00e2mbito tribut\u00e1rio3, assim como da aplica\u00e7\u00e3o das regras de hermen\u00eautica, eis que h\u00e1 remiss\u00e3o \u00e0s opera\u00e7\u00f5es correspondentes aos contratos de m\u00fatuo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Uma primeira quest\u00e3o que poderia ser suscitada, seria a respeito da (in)constitucionalidade de uma hip\u00f3tese de incid\u00eancia que se utiliza de uma locu\u00e7\u00e3o aberta, de car\u00e1ter anal\u00f3gico, que remete a opera\u00e7\u00f5es que correspondam a m\u00fatuo, sem esclarecer se se tratam de m\u00fatuos com elementos contratuais adicionais, mas que preserva seu n\u00facleo causal, ou se abrange quaisquer opera\u00e7\u00f5es que tenham como efeito a movimenta\u00e7\u00e3o de recursos entre pessoas, com obrigatoriedade da sua devolu\u00e7\u00e3o. Esse ponto, conquanto relevante, passa ao largo da discuss\u00e3o no \u00e2mbito do CARF, por for\u00e7a do art. 27-A do Decreto 70.235\/72 e da s\u00famula CARF n. 024.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Avan\u00e7ando, para compreender a incid\u00eancia ou n\u00e3o da regra em testilha, \u00e9 imprescind\u00edvel averiguar se o contrato de conta corrente5 corresponde, em sentido estrito, ao de m\u00fatuo6. Esta verifica\u00e7\u00e3o pressup\u00f5e detida an\u00e1lise dos elementos caracter\u00edsticos das duas figuras: (i) se o contrato \u00e9 t\u00edpico ou at\u00edpico; (ii) se o contrato \u00e9 convencional ou real; (iii) seus objetos; (iv) a natureza das tradi\u00e7\u00f5es; (v) se o contrato \u00e9 bilateral ou unilateral; (vi) se o contrato \u00e9 oneroso ou gratuito; (vii) seu aspecto subjetivo (credores ou devedores); (ix) a cobran\u00e7a de juros e (x) o prazo (determinado ou indeterminado).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em uma primeira an\u00e1lise, observa-se que o contrato de m\u00fatuo consiste em empr\u00e9stimo de coisas fung\u00edveis, por meio do qual o mutu\u00e1rio obriga-se a restituir ao mutuante o que dele recebeu em coisa do mesmo g\u00eanero, qualidade e quantidade, defini\u00e7\u00e3o esta que \u00e9 transportada do Direito Civil (art. 586 do CC), \u00e0 luz do que preconiza o art. 110 do CTN.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O contrato de conta corrente, por sua vez, conquanto expressamente previsto pela lei n. 7.357\/85 (art. 4\u00ba, par\u00e1grafo 2\u00ba, \u201cb\u201d), possui seus elementos t\u00edpicos moldados a partir dos usos, costumes e pr\u00e1ticas do mercado relativas ao neg\u00f3cio (fen\u00f4meno reconhecido como tipicidade social).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Trata-se de esp\u00e9cie contratual da qual derivam contas nas quais s\u00e3o mutuamente registrados d\u00e9bitos e cr\u00e9ditos decorrentes de transfer\u00eancias efetuadas pelos sujeitos contratantes, sendo incerta a exist\u00eancia pr\u00e9via de credores e devedores, que s\u00e3o constatados, habitualmente, somente com a liquida\u00e7\u00e3o e encerramento das contas, ocasi\u00e3o em que (i) n\u00e3o ser\u00e3o apurados valores devidos pelos contratantes em fun\u00e7\u00e3o da correspond\u00eancia entre d\u00e9bitos e cr\u00e9ditos por eles registrados, ou (ii) um deles assumir\u00e1 a posi\u00e7\u00e3o de credor em rela\u00e7\u00e3o ao outro em fun\u00e7\u00e3o de disponibiliza\u00e7\u00e3o de recursos financeiros em montante superior no per\u00edodo em que foram mantidas tais contas7-8<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A partir do posicionamento retratado acima, n\u00e3o se falaria em incid\u00eancia do \u201cIOF-cr\u00e9dito\u201d sobre opera\u00e7\u00f5es derivadas de contratos de conta corrente, sob a justificativa de que este tipo de neg\u00f3cio jur\u00eddico (conta corrente) n\u00e3o guarda qualquer semelhan\u00e7a com os contratos de m\u00fatuo, \u00e0 exce\u00e7\u00e3o da exist\u00eancia de fluxos financeiros nos dois casos. Haveria, na hip\u00f3tese de exig\u00eancia do tributo, emprego de analogia alicer\u00e7ada em crit\u00e9rios econ\u00f4micos para instituir indevida exig\u00eancia tribut\u00e1ria n\u00e3o prevista em lei.9<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em sentido semelhante, \u00e9 poss\u00edvel citar o ac\u00f3rd\u00e3o CARF n. 3402-003.018 segundo o qual os contratos de conta corrente e de m\u00fatuo s\u00e3o essencialmente distintos e o emprego daquele n\u00e3o implica, automaticamente, opera\u00e7\u00e3o de cr\u00e9dito correspondente a este10. No sobredito caso, contudo, restou consignada ressalva no sentido de que incidir\u00e1 o IOF se nos contratos de conta corrente ou na utiliza\u00e7\u00e3o do conta corrente cont\u00e1bil haja, concomitantemente, opera\u00e7\u00f5es de concess\u00e3o de cr\u00e9dito correspondentes a m\u00fatuo. Somente em tais situa\u00e7\u00f5es \u00e9 que haver\u00e1 evento capaz de ensejar a tributa\u00e7\u00e3o pelo IOF, como expressamente estabelecido pelo artigo 13 da Lei n. 9.779\/99.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em sentido diametralmente oposto, entretanto, \u00e9 o posicionamento majorit\u00e1rio refletido em diversos ac\u00f3rd\u00e3os proferidos pelo CARF11, atualmente consolidado pela 3\u00aa Turma da CSRF (ac\u00f3rd\u00e3os n.s 9303\u00ad005.583, 9303-009.257, 9303-009.884, 9303-009.885, 9303-009.960 e 9303-010.184), nos termos do voto a seguir transcrito que, inclusive, reformou o ac\u00f3rd\u00e3o CARF n. 3402\u00ad005.232, alhures comentado:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Contribuinte assevera que as opera\u00e7\u00f5es que levaram aos lan\u00e7amentos tribut\u00e1rios s\u00e3o relativos a conta corrente, cujo objeto \u00e9 a centraliza\u00e7\u00e3o de caixas das empresas, com gest\u00e3o unificada das disponibilidades. Assim, ao tributar tais valores pelo IOF, que fora do mercado financeiro s\u00f3 incide sobre os contratos de m\u00fatuo, a Fiscaliza\u00e7\u00e3o estaria infringindo o princ\u00edpio da legalidade, ao ir na contram\u00e3o do artigo 13 da Lei n\u00ba 9.779, de 1999. Afirma ainda, a inexist\u00eancia de elementos necess\u00e1rios ao contrato de m\u00fatuo, tais como a formaliza\u00e7\u00e3o em contrato escrito, a executoriedade, o risco, os juros, dentre outros.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Discordo do fundamento da decis\u00e3o recorrida, de que haja difer\u00ean\u00e7a [sic] ontol\u00f3gica entre o contrato de m\u00fatuo e o contrato de conta corrente, utilizado para gest\u00e3o de caixa \u00fanico. Com todas as v\u00eanias, entendo, em sentido diametralmente oposto, que a execu\u00e7\u00e3o de um contrato de conta-corrente sempre implica a exist\u00eancia de um contrato de m\u00fatuo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">(&#8230;)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u00c9 claro que todos os recursos postos \u00e0 disposi\u00e7\u00e3o do mutu\u00e1rio\/mandat\u00e1rio, caso n\u00e3o sejam utilizados no pagamento de despesas, devem ser devolvidos ao mutuante\/mandante, o que confirma a ocorr\u00eancia do m\u00fatuo no \u00e2mbito dessa opera\u00e7\u00e3o complexa.\u201d (destaques apostos)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Diante disso, atualmente, a posi\u00e7\u00e3o mantida pelo \u00f3rg\u00e3o julgador respons\u00e1vel por unificar a jurisprud\u00eancia no \u00e2mbito da 3\u00aa Se\u00e7\u00e3o do CARF, \u00e9 no sentido de que a exist\u00eancia de um contrato de conta corrente sucede um contrato de m\u00fatuo, tornando os fluxos financeiros dele decorrentes sujeitos \u00e0 hip\u00f3tese de incid\u00eancia do \u201cIOF-cr\u00e9dito\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Finalmente, vale registrar que a Segunda Turma do Superior Tribunal de Justi\u00e7a (STJ), por ocasi\u00e3o do julgamento do recurso especial n. 1.239.101 \u2013 RJ, em 13.9.2011, asseverou que o art. 13 da lei n. 9779\/99 incide sobre as opera\u00e7\u00f5es realizadas ao abrigo de contrato de conta corrente entre empresas coligadas12.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em que pese a ementa do aludido ac\u00f3rd\u00e3o ilustrar o posicionamento pela incid\u00eancia de IOF sobre fluxos financeiros decorrentes de contratos de conta corrente, \u00e9 imprescind\u00edvel registrar que, ao se analisar a \u00edntegra do ac\u00f3rd\u00e3o, constata-se que a exig\u00eancia no caso concreto decorria de contratos de abertura de cr\u00e9dito em conta corrente, havendo a disponibiliza\u00e7\u00e3o de determinada quantia \u00e0 contratante, com a obriga\u00e7\u00e3o de pagamento do valor sacado em prazo determinado, afastando-se, pois, das opera\u00e7\u00f5es realizadas ao abrigo de contratos de conta corrente habituais, os quais carecem de qualquer previs\u00e3o pr\u00e9via de concess\u00e3o de cr\u00e9dito.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Nesse sentido, apesar da posi\u00e7\u00e3o consolidada do CARF para a mat\u00e9ria, permanece ainda uma poss\u00edvel discuss\u00e3o a ser deflagrada no palco judicial, em especial no \u00e2mbito do STJ.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Este texto n\u00e3o reflete a posi\u00e7\u00e3o institucional do CARF, mas, sim, uma an\u00e1lise dos seus precedentes publicados no site do \u00f3rg\u00e3o, em estudo descritivo, de car\u00e1ter informativo, promovido pelos seus colunistas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">_______________________________________________________________<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">1 E.g. artigos 108, 109 e 110, todos do CTN e art. 11, inciso I, al\u00ednea \u201ca\u201d da lei complementar n. 95\/98.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">2 E.g. artigos 114 e 116, ambos do CTN.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">3 Art. 110 do CTN.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">4 O CARF n\u00e3o \u00e9 competente para se pronunciar sobre a inconstitucionalidade de lei tribut\u00e1ria.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">5 No contrato de conta corrente n\u00e3o se faz um m\u00fatuo nem se abre um cr\u00e9dito, mas se determina o destino de cr\u00e9ditos futuros entre dois sujeitos, adotando uma conta na qual v\u00e3o sendo lan\u00e7ados d\u00e9bitos e cr\u00e9ditos que se excluem mutuamente e cujo saldo s\u00f3 \u00e9 exig\u00edvel quando se d\u00e1 o vencimento do contrato ou mediante extin\u00e7\u00e3o volunt\u00e1ria deste. (Ac\u00f3rd\u00e3o CARF n. 3402\u00ad005.232).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">6 Art. 586. O m\u00fatuo \u00e9 o empr\u00e9stimo de coisas fung\u00edveis. O mutu\u00e1rio \u00e9 obrigado a restituir ao mutuante o que dele recebeu em coisa do mesmo g\u00eanero, qualidade e quantidade.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">7 Os contratos de conta corrente s\u00e3o usualmente utilizados em grupos econ\u00f4micos para a pr\u00e1tica do \u201ccaixa \u00fanico\u201d, que consiste na centraliza\u00e7\u00e3o no controle financeiro das pessoas jur\u00eddicas por meio de uma master account, normalmente gerida por uma holding.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">8 Um quadro sin\u00f3tico elucidativo, com as diferen\u00e7as entre os dois tipos contratuais, pode ser compulsado no Ac\u00f3rd\u00e3o CARF n. 3402-005.232.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">9 Nesse diapas\u00e3o, v. Ac\u00f3rd\u00e3o CARF n. 3101-001.094.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">10 No mesmo sentido, v. 3402-005.232.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">11 Cf. ac\u00f3rd\u00e3os n.s 3402-007.303. 3301-006.706, 3402-006.645, 3401-005.393, 3302-005.802, entre outros.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">12 TRIBUT\u00c1RIO. IOF. TRIBUTA\u00c7\u00c3O DAS OPERA\u00c7\u00d5ES DE CR\u00c9DITO CORRESPONDENTES A M\u00daTUO DE RECURSOS FINANCEIROS ENTRE PESSOAS JUR\u00cdDICAS. ART. 13, DA LEI N. 9.779\/99.<\/span><\/p>\n<ol style=\"text-align: justify;\">\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">O art. 13, da Lei n. 9.779\/99 caracteriza como fato gerador do IOF a ocorr\u00eancia de &#8220;opera\u00e7\u00f5es de cr\u00e9dito correspondentes a m\u00fatuo de recursos financeiros entre pessoas jur\u00eddicas&#8221; e n\u00e3o a espec\u00edfica opera\u00e7\u00e3o de m\u00fatuo. Sendo assim, no contexto do fato gerador do tributo devem ser compreendidas tamb\u00e9m as opera\u00e7\u00f5es realizadas ao abrigo de contrato de conta corrente entre empresas coligadas com a previs\u00e3o de concess\u00e3o de cr\u00e9dito.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif;\">Recurso especial n\u00e3o provido.<\/span><\/li>\n<\/ol>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">(REsp 1239101\/RJ, Rel. Ministro MAURO CAMPBELL MARQUES, SEGUNDA TURMA, julgado em 13\/09\/2011, DJe 19\/09\/2011).<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Conjur &#8211; Por Diego Diniz Ribeiro e D\u00e9bora R. March<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A incid\u00eancia de Imposto sobre Opera\u00e7\u00f5es de Cr\u00e9dito, C\u00e2mbio e [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-203","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7691"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7691"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7691\/revisions"}],"predecessor-version":[{"id":7692,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7691\/revisions\/7692"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7691"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}