{"id":7652,"date":"2020-03-24T11:28:32","date_gmt":"2020-03-24T14:28:32","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=7652"},"modified":"2020-03-24T11:28:32","modified_gmt":"2020-03-24T14:28:32","slug":"itcmd-sp-prazo-de-validade-da-declaracao-de-isencao-do-imposto-passa-a-ser-de-3-anos","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2020\/03\/24\/itcmd-sp-prazo-de-validade-da-declaracao-de-isencao-do-imposto-passa-a-ser-de-3-anos\/","title":{"rendered":"ITCMD\/SP &#8211; PRAZO DE VALIDADE DA DECLARA\u00c7\u00c3O DE ISEN\u00c7\u00c3O DO IMPOSTO PASSA A SER DE 3 ANOS"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Portaria CAT n\u00ba 32\/2020 &#8211; DOE SP de 21.03.2020.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Foram promovidas altera\u00e7\u00f5es na Portaria CAT n\u00ba 15\/2003 , que disciplina o cumprimento das obriga\u00e7\u00f5es acess\u00f3rias e os procedimentos administrativos relacionados com o ITCMD para, entre outras disposi\u00e7\u00f5es, alterar de 1 para 3 anos a validade da &#8220;Declara\u00e7\u00e3o de Isen\u00e7\u00e3o do Imposto sobre Transmiss\u00e3o &#8220;Causa Mortis&#8221; e Doa\u00e7\u00e3o de Quaisquer Bens ou Direitos (ITCMD)&#8221;.Foram ainda alteradas as disposi\u00e7\u00f5es sobre as unidades de atendimento relativas \u00e0 entrega de documenta\u00e7\u00f5es quanto a renova\u00e7\u00e3o da referida Declara\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">(Portaria CAT n\u00ba 32\/2020 &#8211; DOE SP de 21.03.2020).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Editorial IOB<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portaria CAT n\u00ba 32\/2020 &#8211; DOE SP de 21.03.2020.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1Zq","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7652"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7652"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7652\/revisions"}],"predecessor-version":[{"id":7653,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7652\/revisions\/7653"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7652"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}