{"id":7606,"date":"2020-03-23T11:21:37","date_gmt":"2020-03-23T14:21:37","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=7606"},"modified":"2020-03-23T11:21:37","modified_gmt":"2020-03-23T14:21:37","slug":"r-1473-bilhoes-tributaristas-aprovam-pacote-contra-coronavirus-e-sugerem-ampliacao","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2020\/03\/23\/r-1473-bilhoes-tributaristas-aprovam-pacote-contra-coronavirus-e-sugerem-ampliacao\/","title":{"rendered":"R$ 147,3 BILH\u00d5ES &#8211; TRIBUTARISTAS APROVAM PACOTE CONTRA CORONAV\u00cdRUS E SUGEREM AMPLIA\u00c7\u00c3O"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Advogados tributaristas aprovam pacote econ\u00f4mico anunciado por Paulo Guedes.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O an\u00fancio de um pacote de R$ 147,3 bilh\u00f5es pelo ministro Paulo Guedes para manter a economia girando diante da pandemia do coronav\u00edrus foi bem recebido por advogados tributaristas. Eles alertam, contudo, para a necessidade de mais medidas e para o curto prazo de validade de algumas das a\u00e7\u00f5es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Conforme o governo, o plano tem como objetivos principais a prote\u00e7\u00e3o dos mais vulner\u00e1veis, como os idosos, e a manuten\u00e7\u00e3o dos empregos. Dentre essas medidas, est\u00e3o o diferimento do prazo de pagamento do FGTS, a redu\u00e7\u00e3o de 50% nas contribui\u00e7\u00f5es do sistema S e o diferimento da parte da Uni\u00e3o no Simples Nacional, todas com vig\u00eancia prevista de tr\u00eas meses.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Daniel Corr\u00eaa Szelbracikowski, tributarista, s\u00f3cio da Advocacia Dias de Souza, avalia que n\u00e3o se trata propriamente de medidas de est\u00edmulo \u00e0 economia, mas tentativas de preserva\u00e7\u00e3o das empresas e, consequentemente, dos empregos neste momento de crise econ\u00f4mica decorrente da pandemia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cAo postergar os pagamentos do FGTS, de parte do Simples, e reduzir as contribui\u00e7\u00f5es ao sistema S, o governo busca dar um f\u00f4lego aos empres\u00e1rios que ter\u00e3o abrupta diminui\u00e7\u00e3o de receitas neste per\u00edodo e, ainda assim, precisar\u00e3o manter os sal\u00e1rios de seus funcion\u00e1rios em dia. S\u00e3o boas iniciativas. Por\u00e9m, a depender do cen\u00e1rio que se avizinha, talvez seja recomend\u00e1vel estender o diferimento para outros tributos, tais como as contribui\u00e7\u00f5es ao PIS e COFINS e, eventualmente, perdoar no futuro os tributos diferidos\u201d, opina.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Szelbracikowski lembra, ainda, que diferimento \u00e9 mera posterga\u00e7\u00e3o do pagamento. \u201cSe a crise demorar a ir embora, o empres\u00e1rio pode ter muita dificuldade para pagar esses tributos diferidos que se somar\u00e3o aos tributos correntes\u201d, conclui.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O tributarista Richard Edward Dotoli, s\u00f3cio do Costa Tavares Paes Advogados e doutor em Pol\u00edtica Fiscal Tribut\u00e1ria, defende a suspens\u00e3o imediata da reten\u00e7\u00e3o do Imposto de Renda para rendas at\u00e9 R$ 10 mil, permitindo que exista um efetivo recebimento de recursos. \u201cEsse imposto poderia ser cobrado apenas em 2021. \u00c9 poss\u00edvel tamb\u00e9m limitar o prazo da reten\u00e7\u00e3o\u201d, explica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Dotoli tamb\u00e9m v\u00ea a necessidade de desonerar a folha de pagamentos das empresas. \u201cOutra experi\u00eancia de sucesso \u00e9 garantir uma renda m\u00ednima, reduzindo ou postergando, por um per\u00edodo espec\u00edfico (seis meses por exemplo), os tributos incidentes sobre a folha de pagamentos para empregados com rendimentos de at\u00e9 cinco sal\u00e1rios m\u00ednimos. O governo federal garantiria o pagamento de um percentual do sal\u00e1rio, permitindo que o empregador deduza o valor pago a esses empregados, das contribui\u00e7\u00f5es incidentes sobre a folha de sal\u00e1rios\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para Gabriel Lima, tributarista do Nelson Wilians e Advogados Associados, \u201cas medidas s\u00e3o importantes para manter a sa\u00fade financeira das empresas\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">&#8220;\u00c9 importante o governo estar atento para a economia. Al\u00e9m da quest\u00e3o da queda dos valores das empresas que possuem a\u00e7\u00f5es negociadas na bolsa de valores, o com\u00e9rcio local, como lojas varejistas, restaurantes, cinemas etc., est\u00e1 sendo muito afetado. Com a popula\u00e7\u00e3o em casa, o dinheiro deixa de circular. Ent\u00e3o essas medidas s\u00e3o importantes para manter a sa\u00fade financeira das empresas, o fluxo de caixa e, principalmente, manter a economia do pa\u00eds funcionando\u201d, diz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Lima destaca ainda que Estados e munic\u00edpios deveriam criar facilidades para pagamentos de tributos, como ICMS e ISS.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">J\u00e1 a tributarista Erika Tukiama, s\u00f3cia de Chiarottino e Nicoletti Advogados, concorda que as medidas propostas pelo governo s\u00e3o, em geral, positivas. \u201cMas poderiam incluir algo de car\u00e1ter mais abrangente, que envolvesse a participa\u00e7\u00e3o das empresas e empres\u00e1rios em geral, tal como a concess\u00e3o de incentivos fiscais para aqueles que comprovadamente colocassem suas estruturas produtivas e de servi\u00e7os \u00e0 disposi\u00e7\u00e3o de iniciativas de combate \u00e0 pandemia, a exemplo do que a LVMH fez na Fran\u00e7a, ao alocar parte da sua produ\u00e7\u00e3o de perfumes para a manufatura de \u00e1lcool em gel para doa\u00e7\u00e3o ao governo\u201d, assinala.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Conjur<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Advogados tributaristas aprovam pacote econ\u00f4mico anunciado por Paulo Guedes.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1YG","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7606"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7606"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7606\/revisions"}],"predecessor-version":[{"id":7607,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7606\/revisions\/7607"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7606"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}