{"id":7572,"date":"2020-03-20T11:14:54","date_gmt":"2020-03-20T14:14:54","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=7572"},"modified":"2020-03-20T11:14:54","modified_gmt":"2020-03-20T14:14:54","slug":"plantao-extraordinario-resolucao-do-cnj-suspende-prazos-processuais-em-todo-pais-ate-30-de-abril","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2020\/03\/20\/plantao-extraordinario-resolucao-do-cnj-suspende-prazos-processuais-em-todo-pais-ate-30-de-abril\/","title":{"rendered":"PLANT\u00c3O EXTRAORDIN\u00c1RIO &#8211; RESOLU\u00c7\u00c3O DO CNJ SUSPENDE PRAZOS PROCESSUAIS EM TODO PA\u00cdS AT\u00c9 30 DE ABRIL"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Resolu\u00e7\u00e3o ser\u00e1 assinada pelo presidente do STF e CNJ, ministro Dias Toffoli<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Conselho Nacional de Justi\u00e7a aprovou nesta quinta-feira (19\/3) uma resolu\u00e7\u00e3o que suspende os prazos processuais em todas as jurisdi\u00e7\u00f5es do pa\u00eds at\u00e9 30 de abril. Trata-se da Resolu\u00e7\u00e3o 313\/19, que n\u00e3o se aplica ao STF e \u00e0 Justi\u00e7a Eleitoral. Ela \u00e9 assinada pelo ministro Dias Toffoli, presidente do Supremo Tribunal Federal e do CNJ.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O objetivo principal \u00e9 estabelecer um regime de &#8220;Plant\u00e3o Extraordin\u00e1rio&#8221; na Justi\u00e7a, de modo a uniformizar o funcionamento dos servi\u00e7os judici\u00e1rios em todo o pa\u00eds e garantir o acesso \u00e0 Justi\u00e7a durante a crise desencadeada pela propaga\u00e7\u00e3o do novo coronav\u00edrus.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O &#8220;Plant\u00e3o Extraordin\u00e1rio&#8221; implica em suspens\u00e3o do trabalho presencial de magistrados, servidores, estagi\u00e1rios e colaboradores nas unidades judici\u00e1rias. Mas fica assegurada a manuten\u00e7\u00e3o dos servi\u00e7os essenciais. Isto \u00e9, haver\u00e1 uma escala presencial a ser determinada por cada tribunal, mas dela ser\u00e3o exclu\u00eddos magistrados, servidores e colaboradores identificados como de grupo de risco.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Durante o &#8220;Plant\u00e3o Extraordin\u00e1rio&#8221;, o hor\u00e1rio de funcionamento ser\u00e1 o mesmo do expediente forense regular, estabelecido pelo respectivo Tribunal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Cada tribunal dever\u00e1 definir as atividades essenciais a serem prestadas, devendo ser garantidas, &#8220;minimamente&#8221;: a distribui\u00e7\u00e3o de processos judiciais e administrativos, com prioridade aos procedimentos de urg\u00eancia; a manuten\u00e7\u00e3o de servi\u00e7os destinados \u00e0 expedi\u00e7\u00e3o e publica\u00e7\u00e3o de atos judiciais e administrativos; o atendimento aos advogados, procuradores, defensores p\u00fablicos, membros do Minist\u00e9rio P\u00fablico e da pol\u00edcia judici\u00e1ria, de forma prioritariamente remota e, excepcionalmente, de forma presencial; a manuten\u00e7\u00e3o dos servi\u00e7os de pagamento, seguran\u00e7a institucional, comunica\u00e7\u00e3o, tecnologia da informa\u00e7\u00e3o e sa\u00fade; e outras as atividades jurisdicionais de urg\u00eancia previstas pela Resolu\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Outras medidas<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Al\u00e9m disso, fica suspenso o atendimento presencial de partes, advogados e interessados, que dever\u00e1 ser realizado remotamente pelos meios tecnol\u00f3gicos dispon\u00edveis.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Durante o plant\u00e3o excepcional, a aprecia\u00e7\u00e3o de algumas mat\u00e9rias fica garantida. S\u00e3o elas:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Habeas Corpus e mandado de seguran\u00e7a;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Medidas liminares e de antecipa\u00e7\u00e3o de tutela de qualquer natureza, inclusive no \u00e2mbito dos juizados especiais;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Comunica\u00e7\u00f5es de pris\u00e3o em flagrante, pedidos de concess\u00e3o de liberdade provis\u00f3ria, imposi\u00e7\u00e3o e substitui\u00e7\u00e3o de medidas cautelares diversas da pris\u00e3o, e desinterna\u00e7\u00e3o;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Representa\u00e7\u00e3o da autoridade policial ou do Minist\u00e9rio P\u00fablico visando \u00e0 decreta\u00e7\u00e3o de pris\u00e3o preventiva ou tempor\u00e1ria;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Pedidos de busca e apreens\u00e3o de pessoas, bens ou valores, intercepta\u00e7\u00f5es telef\u00f4nicas e telem\u00e1ticas, desde que objetivamente comprovada a urg\u00eancia;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Pedidos de alvar\u00e1s, pedidos de levantamento de import\u00e2ncia em dinheiro ou valores, substitui\u00e7\u00e3o de garantias e libera\u00e7\u00e3o de bens apreendidos, pagamento de precat\u00f3rios, Requisi\u00e7\u00f5es de Pequeno Valor \u2014 RPVs e expedi\u00e7\u00e3o de guias de dep\u00f3sito;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Pedidos de acolhimento familiar e institucional e de desacolhimento;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Pedidos de progress\u00e3o e regress\u00e3o cautelar de regime prisional, concess\u00e3o de livramento condicional, indulto e comuta\u00e7\u00e3o de penas;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Pedidos de crema\u00e7\u00e3o de cad\u00e1ver, exuma\u00e7\u00e3o e inuma\u00e7\u00e3o;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">* Autoriza\u00e7\u00e3o de viagem de crian\u00e7as e adolescentes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Resolu\u00e7\u00e3o 313\/2020 CNJ<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><a href=\"https:\/\/www.conjur.com.br\/dl\/resolucao-313-19-marco-2020-cnj-cnj.pdf\">https:\/\/www.conjur.com.br\/dl\/resolucao-313-19-marco-2020-cnj-cnj.pdf<\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Conjur &#8211; Por Andr\u00e9 Boselli<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolu\u00e7\u00e3o ser\u00e1 assinada pelo presidente do STF e CNJ, ministro [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1Y8","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7572"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7572"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7572\/revisions"}],"predecessor-version":[{"id":7573,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7572\/revisions\/7573"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7572"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}