{"id":7449,"date":"2020-03-17T11:40:54","date_gmt":"2020-03-17T14:40:54","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=7449"},"modified":"2020-03-17T11:40:54","modified_gmt":"2020-03-17T14:40:54","slug":"tributos-e-contribuicoes-federais-previdenciaria-ministerio-da-economia-anuncia-medidas-para-diminuir-o-impacto-do-coronavirus-no-pais","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2020\/03\/17\/tributos-e-contribuicoes-federais-previdenciaria-ministerio-da-economia-anuncia-medidas-para-diminuir-o-impacto-do-coronavirus-no-pais\/","title":{"rendered":"TRIBUTOS E CONTRIBUI\u00c7\u00d5ES FEDERAIS\/PREVIDENCI\u00c1RIA &#8211; MINIST\u00c9RIO DA ECONOMIA ANUNCIA MEDIDAS PARA DIMINUIR O IMPACTO DO CORONAV\u00cdRUS NO PA\u00cdS"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Covid 19 &#8211; Plano divulgado pelo ministro Paulo Guedes injetar\u00e1 R$ 147,3 bilh\u00f5es em tr\u00eas meses.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O ministro da Economia, Paulo Guedes, anunciou no in\u00edcio da noite desta segunda-feira (16\/3) um conjunto de medidas emergenciais para prote\u00e7\u00e3o da popula\u00e7\u00e3o mais vulner\u00e1vel \u00e0 pandemia do coronav\u00edrus e \u00e0 manuten\u00e7\u00e3o de empregos. Segundo o ministro ser\u00e3o disponibilizados, rapidamente, R$ 147,3 bilh\u00f5es, sendo R$ 83,4 bilh\u00f5es direcionados para a popula\u00e7\u00e3o mais idosa, justamente a mais afetada pela pandemia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cA sa\u00fade do povo brasileiro est\u00e1 acima e al\u00e9m das disputas pol\u00edticas\u201d, salientou o ministro ao explicar as medidas. Segundo Guedes, apesar da magnitude, esse \u00e9 apenas um esfor\u00e7o inicial. Quase R$ 60 bilh\u00f5es ir\u00e3o para a manuten\u00e7\u00e3o de empregos, com o governo postergando, por tr\u00eas meses, o prazo que as empresas t\u00eam para o pagamento ao FGTS e tamb\u00e9m a parte referente \u00e0 parcela da Uni\u00e3o no Simples Nacional. Durante esse per\u00edodo de tr\u00eas meses, as contribui\u00e7\u00f5es devidas ao Sistema S sofrer\u00e3o redu\u00e7\u00e3o de 50%.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para os idosos, a principal medida foi a antecipa\u00e7\u00e3o da segunda parcela do 13\u00ba sal\u00e1rio para o m\u00eas de maio, a ser pago aos aposentados e pensionistas do Instituto Nacional do Seguro Social (INSS). A antecipa\u00e7\u00e3o da primeira parcela para o m\u00eas de abril j\u00e1 tinha sido anunciada. Al\u00e9m disso, o governo vai transferir os valores n\u00e3o sacados do PIS\/Pasep para o Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) para permitir novos saques. Ainda com a preocupa\u00e7\u00e3o de injetar recursos na economia o governo vai antecipar para junho o pagamento do abono salarial.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O secret\u00e1rio Especial de Fazenda, Waldery Rodrigues, disse que o governo poder\u00e1 encaminhar uma medida provis\u00f3ria para tratar rapidamente de uma nova modalidade de saque do FGTS, estabelecendo um teto para isso. \u201cO valor ainda est\u00e1 sendo estudado e ser\u00e1 divulgado em breve\u201d, garantiu.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O ministro aproveitou o an\u00fancio das medidas emergenciais para reafirmar a import\u00e2ncia das reformas estruturantes para a economia brasileira. \u201c Com as reformas estruturantes voc\u00ea aumenta a resili\u00eancia da economia\u201d, disse. Guedes citou o Pacto Federativo, o PL da Eletrobr\u00e1s e o chamado Plano Mansueto como fundamentais. \u201cAs reformas nos permitir\u00e3o abrir espa\u00e7o fiscal e aumentar nossa capacidade de defesa\u201d, observou.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Guedes ainda ressaltou as medidas aprovadas pelo Conselho Monet\u00e1rio Nacional (CMN) pelos membros votantes (ministro da Economia, Paulo Guedes; presidente do Banco Central, Roberto Campos Neto; e Secret\u00e1rio Especial de Fazenda, Waldery Rodrigues). A primeira facilita a renegocia\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9ditos de empresas e de fam\u00edlias ao dispensar os bancos de aumentarem o provisionamento, caso essa repactua\u00e7\u00e3o ocorra nos pr\u00f3ximos seis meses. Outra medida expande a capacidade de utiliza\u00e7\u00e3o de capital dos bancos para que esses tenham melhores condi\u00e7\u00f5es para realizar as eventuais renegocia\u00e7\u00f5es e de manter o fluxo de concess\u00e3o de cr\u00e9dito, baixando a necessidade de capital pr\u00f3prio para a alavancagem das opera\u00e7\u00f5es. Isso possibilitar\u00e1 aumentar a capacidade de concess\u00e3o de cr\u00e9dito em torno de R$ 637 bilh\u00f5es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para o combate direto \u00e0 pandemia do coronav\u00edrus, o Minist\u00e9rio da Economia destinar\u00e1 o saldo do fundo do DPVAT para o Sistema \u00danico de Sa\u00fade (s\u00e3o mais R$ 4,5 bilh\u00f5es), reduzir\u00e1 a zero as al\u00edquotas de importa\u00e7\u00e3o de produtos de uso m\u00e9dico-hospitalar, al\u00e9m da desonera\u00e7\u00e3o tempor\u00e1ria de IPI para bens produzidos internamente ou importados, que sejam necess\u00e1rios ao combate do Covid-19.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Participaram do an\u00fancio das medidas emergenciais os secret\u00e1rios especiais da Receita Federal, Jos\u00e9 Barroso Tostes; da Fazenda, Waldery Rodrigues; da Produtividade, Emprego e Competividade, Carlos Da Costa; e da Previd\u00eancia e Trabalho, Bruno Bianco, al\u00e9m do secret\u00e1rio-executivo, Marcelo Guaranys e do secret\u00e1rio do Tesouro Nacional, Mansueto Almeida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Confira o resumo das medidas anunciadas: <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">http:\/\/www.economia.gov.br\/central-de-conteudos\/apresentacoes\/2020\/apresentacao_medidas.pdf\/view<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Minist\u00e9rio da Economia<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Covid 19 &#8211; Plano divulgado pelo ministro Paulo Guedes injetar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1W9","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7449"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7449"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7449\/revisions"}],"predecessor-version":[{"id":7450,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7449\/revisions\/7450"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7449"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}