{"id":7435,"date":"2020-03-16T11:55:51","date_gmt":"2020-03-16T14:55:51","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=7435"},"modified":"2020-03-16T11:55:51","modified_gmt":"2020-03-16T14:55:51","slug":"prescricao-da-pretensao-punitiva-na-acao-penal-nao-impede-andamento-de-acao-indenizatoria-no-juizo-civel","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2020\/03\/16\/prescricao-da-pretensao-punitiva-na-acao-penal-nao-impede-andamento-de-acao-indenizatoria-no-juizo-civel\/","title":{"rendered":"PRESCRI\u00c7\u00c3O DA PRETENS\u00c3O PUNITIVA NA A\u00c7\u00c3O PENAL N\u00c3O IMPEDE ANDAMENTO DE A\u00c7\u00c3O INDENIZAT\u00d3RIA NO JU\u00cdZO C\u00cdVEL"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para a Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ), a prescri\u00e7\u00e3o da a\u00e7\u00e3o penal n\u00e3o afasta o interesse processual no exerc\u00edcio da pretens\u00e3o indenizat\u00f3ria por meio de a\u00e7\u00e3o civil ex delicto (a\u00e7\u00e3o movida pela v\u00edtima na Justi\u00e7a c\u00edvel para ser indenizada pelo dano decorrente do crime).<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Com base nesse entendimento, o colegiado negou provimento a recurso em que se questionava ac\u00f3rd\u00e3o do Tribunal de Justi\u00e7a de S\u00e3o Paulo (TJSP), o qual decidiu ser poss\u00edvel a tramita\u00e7\u00e3o de a\u00e7\u00e3o civil com pedido de indeniza\u00e7\u00e3o por danos morais e materiais causados a uma v\u00edtima de les\u00e3o corporal grave, mesmo tendo sido reconhecida a prescri\u00e7\u00e3o no ju\u00edzo criminal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Segundo os autos, a v\u00edtima sofreu agress\u00f5es f\u00edsicas em 2004. Em 2010, o agredido ajuizou a a\u00e7\u00e3o civil ex delicto contra seus agressores. Em 2014, por\u00e9m, ap\u00f3s senten\u00e7a penal condenat\u00f3ria por les\u00e3o corporal grave, a pena dos r\u00e9us foi extinta pela prescri\u00e7\u00e3o retroativa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">No recurso ao STJ, os supostos agressores alegaram que a a\u00e7\u00e3o indenizat\u00f3ria s\u00f3 poderia ter sido ajuizada se houvesse condena\u00e7\u00e3o criminal transitada em julgado. Sustentaram ainda que a pretens\u00e3o reparat\u00f3ria estaria prescrita.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Independ\u00eancia relativa<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">&#8220;A decreta\u00e7\u00e3o da prescri\u00e7\u00e3o da pretens\u00e3o punitiva do Estado impede, t\u00e3o somente, a forma\u00e7\u00e3o do t\u00edtulo executivo judicial na esfera penal, indispens\u00e1vel ao exerc\u00edcio da pretens\u00e3o execut\u00f3ria pelo ofendido, mas n\u00e3o fulmina o interesse processual no exerc\u00edcio da pretens\u00e3o indenizat\u00f3ria a ser deduzida no ju\u00edzo c\u00edvel pelo mesmo fato&#8221;, esclareceu a relatora do recurso, ministra Nancy Andrighi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">De acordo com a ministra, o ordenamento jur\u00eddico brasileiro estabelece a exist\u00eancia de relativa independ\u00eancia entre as jurisdi\u00e7\u00f5es c\u00edvel e penal. Segundo ela, quem pretende pedir ressarcimento por danos sofridos com a pr\u00e1tica de um delito pode escolher ajuizar a\u00e7\u00e3o c\u00edvel de indeniza\u00e7\u00e3o ou aguardar o desfecho da a\u00e7\u00e3o penal, para, ent\u00e3o, liquidar ou executar o t\u00edtulo judicial eventualmente constitu\u00eddo pela senten\u00e7a penal condenat\u00f3ria transitada em julgado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A relatora explicou ainda que a pretens\u00e3o da a\u00e7\u00e3o civil ex delicto &#8220;se vincula \u00e0 ocorr\u00eancia de um fato delituoso que causou danos, ainda que tal fato e sua autoria n\u00e3o tenham sido definitivamente apurados no ju\u00edzo criminal&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Prescri\u00e7\u00e3o suspensa<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Nancy Andrighi destacou que o C\u00f3digo Civil de 2002 disp\u00f5e que, quando a a\u00e7\u00e3o civil se originar de fato que deva ser apurado no ju\u00edzo criminal, n\u00e3o correr\u00e1 a prescri\u00e7\u00e3o antes da respectiva senten\u00e7a definitiva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Assim, afirmou a relatora, embora a a\u00e7\u00e3o de conhecimento possa ser ajuizada a partir do momento em que nasce a pretens\u00e3o do ofendido, o prazo de prescri\u00e7\u00e3o da pretens\u00e3o reparat\u00f3ria se suspende quando o mesmo fato come\u00e7a a ser apurado na esfera criminal. Da\u00ed em diante, o ofendido passa a ter tamb\u00e9m a op\u00e7\u00e3o de liquidar ou executar eventual senten\u00e7a penal condenat\u00f3ria.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ao negar provimento ao recurso especial, por unanimidade, a turma observou que a pretens\u00e3o da v\u00edtima da agress\u00e3o n\u00e3o era de liquida\u00e7\u00e3o ou execu\u00e7\u00e3o da senten\u00e7a penal transitada em julgado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Segundo Nancy Andrighi, a v\u00edtima quer somente ver reparados os danos que lhe foram causados pelos agressores, valendo-se, para ajuizar a a\u00e7\u00e3o civil ex delicto, apenas do fato de terem sido condenados em primeira inst\u00e2ncia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ac\u00f3rd\u00e3o REsp1802170<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: STJ<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Para a Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ), [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-1VV","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7435"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7435"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7435\/revisions"}],"predecessor-version":[{"id":7436,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7435\/revisions\/7436"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7435"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}