{"id":16180,"date":"2021-04-27T11:19:25","date_gmt":"2021-04-27T14:19:25","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=16180"},"modified":"2021-04-27T11:19:25","modified_gmt":"2021-04-27T14:19:25","slug":"para-segunda-turma-suspensao-de-processos-nao-termina-logo-apos-julgamento-de-irdr","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2021\/04\/27\/para-segunda-turma-suspensao-de-processos-nao-termina-logo-apos-julgamento-de-irdr\/","title":{"rendered":"PARA SEGUNDA TURMA, SUSPENS\u00c3O DE PROCESSOS N\u00c3O TERMINA LOGO AP\u00d3S JULGAMENTO DE IRDR"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A Segunda Turma do Superior Tribunal de Justi\u00e7a (STJ) decidiu que os processos cujo andamento foi suspenso em raz\u00e3o da instaura\u00e7\u00e3o de Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) n\u00e3o voltam a tramitar imediatamente ap\u00f3s a conclus\u00e3o do julgamento da quest\u00e3o controvertida na Corte de segunda inst\u00e2ncia, sendo necess\u00e1rio aguardar eventual an\u00e1lise dos recursos especial e extraordin\u00e1rio pelos tribunais superiores. Para o colegiado, entretanto, n\u00e3o \u00e9 preciso manter a suspens\u00e3o at\u00e9 o tr\u00e2nsito em julgado desses recursos.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">&#8220;Com a manuten\u00e7\u00e3o da suspens\u00e3o dos processos pendentes at\u00e9 o julgamento dos recursos pelos tribunais superiores, assegura-se a homogeneiza\u00e7\u00e3o das decis\u00f5es judiciais sobre casos semelhantes, garantindo-se a seguran\u00e7a jur\u00eddica e a isonomia de tratamento dos jurisdicionados&#8221;, afirmou o ministro Og Fernandes, relator.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O recurso chegou ao STJ ap\u00f3s o Tribunal de Justi\u00e7a de Santa Catarina (TJSC) entender ser poss\u00edvel aplicar a um mandado de seguran\u00e7a, de forma imediata, a tese fixada em IRDR. A posi\u00e7\u00e3o do TJSC foi baseada em jurisprud\u00eancia do Supremo Tribunal Federal (STF) no sentido de que \u00e9 v\u00e1lida a aplica\u00e7\u00e3o imediata da decis\u00e3o tomada em \u00e2mbito de repercuss\u00e3o geral, independentemente de seu tr\u00e2nsito em julgado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Sistem\u00e1ticas diferentes<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O ministro Og Fernandes, entretanto, entendeu ser necess\u00e1rio distinguir o tratamento dado pelo C\u00f3digo de Processo Civil ao IRDR e aos recursos repetitivos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">No caso dos repetitivos, explicou o relator, os artigos 1.039 e 1.040 do CPC condicionam o prosseguimento dos processos pendentes apenas \u00e0 publica\u00e7\u00e3o do ac\u00f3rd\u00e3o paradigma. Al\u00e9m disso, apontou, os ac\u00f3rd\u00e3os proferidos sob a sistem\u00e1tica dos recursos repetitivos n\u00e3o s\u00e3o impugn\u00e1veis por recursos com efeito suspensivo autom\u00e1tico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Segundo o magistrado, situa\u00e7\u00e3o diferente ocorre no IRDR, pois o artigo 982, par\u00e1grafo 5\u00ba, do CPC estabelece que a suspens\u00e3o dos processos cessa apenas se n\u00e3o for interposto recurso especial ou recurso extraordin\u00e1rio contra a decis\u00e3o proferida no incidente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">&#8220;Al\u00e9m disso, h\u00e1 previs\u00e3o expressa, nos par\u00e1grafos 1\u00ba e 2\u00ba do artigo 987 do CPC, de que os recursos extraordin\u00e1rio e especial contra ac\u00f3rd\u00e3o que julga o incidente em quest\u00e3o t\u00eam efeito suspensivo autom\u00e1tico (ope legis), bem como de que a tese jur\u00eddica adotada pelo STJ ou pelo STF ser\u00e1 aplicada, no territ\u00f3rio nacional, a todos os processos individuais ou coletivos que versem sobre id\u00eantica quest\u00e3o de direito&#8221;, afirmou o ministro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Multiplicidade de recursos<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">De acordo com Og Fernandes, tanto o IRDR quanto os recursos repetitivos comp\u00f5em o mesmo microssistema de julgamento de demandas de massa. Entretanto, ponderou o relator, enquanto o IRDR ainda pode ser combatido pelos recursos aos tribunais superiores \u2013 os quais, quando julgados, uniformizam a controv\u00e9rsia em todo o pa\u00eds \u2013, os recursos repetitivos apenas podem ser objeto de embargos de declara\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ainda segundo o ministro, admitir o prosseguimento dos processos suspensos antes do julgamento dos recursos contra o ac\u00f3rd\u00e3o do IRDR poderia gerar uma multiplicidade de atos processuais desnecess\u00e1rios, especialmente recursos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">&#8220;Isso porque, caso se admita a continua\u00e7\u00e3o dos processos at\u00e9 ent\u00e3o suspensos, os sujeitos inconformados com o posicionamento firmado no julgamento do IRDR ter\u00e3o que interpor recursos a fim de evitar a forma\u00e7\u00e3o de coisa julgada antes do posicionamento definitivo dos tribunais superiores&#8221;, concluiu o magistrado ao reformar o ac\u00f3rd\u00e3o do TJSC.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">REsp1869867<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: STJ<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Segunda Turma do Superior Tribunal de Justi\u00e7a (STJ) decidiu [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-4cY","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16180"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16180"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16180\/revisions"}],"predecessor-version":[{"id":16181,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16180\/revisions\/16181"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16180"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}