{"id":16173,"date":"2021-04-27T11:13:57","date_gmt":"2021-04-27T14:13:57","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=16173"},"modified":"2021-04-27T11:13:57","modified_gmt":"2021-04-27T14:13:57","slug":"irpf-2021-veja-quais-doencas-graves-garantem-isencao-e-saiba-como-comprovar","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2021\/04\/27\/irpf-2021-veja-quais-doencas-graves-garantem-isencao-e-saiba-como-comprovar\/","title":{"rendered":"IRPF 2021: VEJA QUAIS DOEN\u00c7AS GRAVES GARANTEM ISEN\u00c7\u00c3O E SAIBA COMO COMPROVAR"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para solicitar a isen\u00e7\u00e3o do Imposto de Renda, \u00e9 preciso estar enquadrado em algumas regras.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">As situa\u00e7\u00f5es que garantem isen\u00e7\u00e3o do imposto de renda geram d\u00favidas, principalmente quando se trata de doen\u00e7as. Isso porque, os gatos do paciente com tratamento, em muitos casos, \u00e9 alto. H\u00e1 uma situa\u00e7\u00e3o diferenciada, prevista por lei, tamb\u00e9m para aposentados e pensionistas do Instituto Nacional do Seguro Social (INSS) .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Lei n\u00ba 7.713\/88, que disp\u00f5e sobre a isen\u00e7\u00e3o do Imposto de Renda, assegura aos portadores de doen\u00e7as graves o direito \u00e0 obter a isen\u00e7\u00e3o do IRPF perante os valores recebidos pela aposentadoria, pens\u00e3o ou reforma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">As doen\u00e7as que permitem isen\u00e7\u00e3o s\u00e3o as seguintes:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">AIDS (S\u00edndrome da Imunodefici\u00eancia Adquirida);<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Aliena\u00e7\u00e3o mental;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Cardiopatia grave;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Cegueira;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Contamina\u00e7\u00e3o por radia\u00e7\u00e3o;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Doen\u00e7a de Paget em estados avan\u00e7ados (Oste\u00edte deformante);<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Doen\u00e7a de Parkinson;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Esclerose m\u00faltipla;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Espondiloartrose anquilosante;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Fibrose c\u00edstica (Mucoviscidose);<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Hansen\u00edase;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Nefropatia grave;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Hepatopatia grave (observa\u00e7\u00e3o: em casos de hepatopatia grave ser\u00e3o isentos apenas os rendimentos auferidos a partir de 01\/01\/2005);<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Neoplasia maligna;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Paralisia irrevers\u00edvel e incapacitante;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">S\u00edndrome de Talidomida;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Tuberculose ativa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os contribuintes que possuem qualquer uma dessas doen\u00e7as, pode solicitar a isen\u00e7\u00e3o do IR 2021. Para isso, \u00e9 preciso passar por uma per\u00edcia m\u00e9dica com algum servi\u00e7o m\u00e9dico oficial da Uni\u00e3o, Estado ou Munic\u00edpio, para conseguir um laudo que constate a doen\u00e7a pela qual \u00e9 acometido.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Laudo pericial<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para quem vai solicitar o laudo m\u00e9dico de comprova\u00e7\u00e3o, \u00e9 importante saber o que precisa constar para que o documento seja aceito.\u00a0 \u00c9 exigida a data em que contraiu a doen\u00e7a, e se n\u00e3o for poss\u00edvel informar a data precisa em que a doen\u00e7a foi contra\u00edda, a data de emiss\u00e3o do laudo basta para ser considerada. Al\u00e9m disso, tamb\u00e9m \u00e9 preciso contar se a doen\u00e7a pode ser controlada, indicando prazo de validade do c\u00e1lculo, lembrando que o laudo tamb\u00e9m deve ser apresentado na fonte pagadora.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Depois de elaborado, o laudo m\u00e9dico precisa ser entregue em uma das ag\u00eancias do INSS e n\u00e3o para a Receita Federal. A autarquia ser\u00e1 respons\u00e1vel por avaliar a veracidade dos laudos e da enfermidade mencionada, de maneira que, se for comprovada a situa\u00e7\u00e3o, o contribuinte ser\u00e1 isento do pagamento do Imposto de Renda no sistema da Receita Federal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Fonte: Cont\u00e1beis \u2013 Por Amanda Santos<\/span> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para solicitar a isen\u00e7\u00e3o do Imposto de Renda, \u00e9 preciso [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-4cR","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16173"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16173"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16173\/revisions"}],"predecessor-version":[{"id":16174,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16173\/revisions\/16174"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16173"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}