{"id":16150,"date":"2021-04-26T11:48:18","date_gmt":"2021-04-26T14:48:18","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=16150"},"modified":"2021-04-26T11:48:18","modified_gmt":"2021-04-26T14:48:18","slug":"pessoa-juridica-com-recuperacao-judicial-tem-ate-quinta-29-para-aproveitar-as-condicoes-diferenciadas-de-negociacao","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2021\/04\/26\/pessoa-juridica-com-recuperacao-judicial-tem-ate-quinta-29-para-aproveitar-as-condicoes-diferenciadas-de-negociacao\/","title":{"rendered":"PESSOA JUR\u00cdDICA COM RECUPERA\u00c7\u00c3O JUDICIAL TEM AT\u00c9 QUINTA (29) PARA APROVEITAR AS CONDI\u00c7\u00d5ES DIFERENCIADAS DE NEGOCIA\u00c7\u00c3O"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os interessados dever\u00e3o acessar o portal REGULARIZE para apresentar a proposta de Transa\u00e7\u00e3o Individual ou aderir \u00e0 Transa\u00e7\u00e3o Excepcional com o prazo para pagamento ampliado<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Termina na pr\u00f3xima quinta-feira (29) o prazo para os contribuintes com recupera\u00e7\u00e3o judicial j\u00e1 concedida (art. 58 da Lei 11.101\/2005) aproveitarem as condi\u00e7\u00f5es diferenciadas para negocia\u00e7\u00e3o \u2013 que concedem prazo ampliado para pagamento em at\u00e9 120 meses e descontos que podem chegar a 70% do valor total da d\u00edvida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A recuperanda interessada precisa estar atenta a esse prazo, como foi estabelecido por lei \u2013 art. 5, par\u00e1grafo 4\u00ba, da Lei n. 14.112\/2020 \u2013, a PGFN n\u00e3o tem autonomia para prorrog\u00e1-lo por meio de portaria.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ap\u00f3s 29 de abril, recuperanda somente poder\u00e1 aderir \u00e0 transa\u00e7\u00e3o nas condi\u00e7\u00f5es gerais previstas na Lei n. 13.988\/2020, ou seja, n\u00e3o poder\u00e1 usufruir os benef\u00edcios previstos no art. 10-C da Lei 10.522\/2002.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Confira que os benef\u00edcios e entenda como proceder:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Transa\u00e7\u00e3o Excepcional<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Essa modalidade est\u00e1 dispon\u00edvel para os contribuintes em geral, desde que atendam aos requisitos exigidos. Contudo, tratando-se da pessoa jur\u00eddica recuperanda (art. 58 da Lei 11.101\/2005), \u00e9 poss\u00edvel usufruir de condi\u00e7\u00f5es mais ben\u00e9ficas, desde que providenciada a ades\u00e3o dentro do prazo legal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para aderir, o primeiro passo \u00e9 preencher o formul\u00e1rio de receitas e rendimentos. O formul\u00e1rio est\u00e1 dispon\u00edvel no portal REGULARIZE, na op\u00e7\u00e3o Negociar D\u00edvida &gt; Acessar o Sistema de Negocia\u00e7\u00f5es.\u00a0 No Sistema de Negocia\u00e7\u00f5es, clicar no menu Declara\u00e7\u00e3o de Receita\/Rendimento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Feita a declara\u00e7\u00e3o, clicar no menu superior Ades\u00e3o &gt; Transa\u00e7\u00e3o. Em seguida, selecione a modalidade espec\u00edfica prevista para as recuperandas, com os benef\u00edcios do art. 10-C, da Lei n\u00ba 10.522\/2002.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ap\u00f3s realizar o pedido de ades\u00e3o, pagar a primeira presta\u00e7\u00e3o at\u00e9 a data de vencimento, que \u00e9 o \u00faltimo dia \u00fatil do m\u00eas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Fica o alerta! Para garantir que o sistema ir\u00e1 calcular devidamente o desconto e o prazo, levando em considera\u00e7\u00e3o a situa\u00e7\u00e3o especial de contribuinte em recupera\u00e7\u00e3o judicial, consulte aqui no sistema da Receita Federal do Brasil (RFB) se essa informa\u00e7\u00e3o j\u00e1 est\u00e1 anotada no cadastro do CNPJ. Se n\u00e3o constar, o representante legal dever\u00e1 providenciar a atualiza\u00e7\u00e3o dessa situa\u00e7\u00e3o perante a RFB, de acordo com o art. 24 da Instru\u00e7\u00e3o Normativa RFB n. 1863, de 27 de dezembro de 2018.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Importante destacar que ades\u00f5es realizadas ap\u00f3s 29 de abril ser\u00e3o canceladas pela PGFN.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Transa\u00e7\u00e3o Individual<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">No caso de proposta individual, n\u00e3o \u00e9 necess\u00e1rio que o acordo de transa\u00e7\u00e3o individual seja formalizado at\u00e9 o dia 29 de abril, mas sim que a proposta seja apresentada tempestivamente pela pessoa jur\u00eddica recuperanda (art. 58 da Lei 11.101\/2005).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para apresentar a proposta, basta acessar o portal REGULARIZE e clicar em Negociar D\u00edvida &gt; Acordo de Transa\u00e7\u00e3o Individual. A orienta\u00e7\u00e3o completa com a documenta\u00e7\u00e3o exigida pode ser acessada aqui!<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Fonte: PGFN &#8211; Por Fernando Olivan &#8211; Comunica\u00e7\u00e3o Fenacon<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os interessados dever\u00e3o acessar o portal REGULARIZE para apresentar a [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-4cu","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16150"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16150"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16150\/revisions"}],"predecessor-version":[{"id":16151,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16150\/revisions\/16151"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16150"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}