{"id":16106,"date":"2021-04-22T11:07:34","date_gmt":"2021-04-22T14:07:34","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=16106"},"modified":"2021-04-22T11:07:34","modified_gmt":"2021-04-22T14:07:34","slug":"inpi-pode-anular-patente-de-remedio-a-base-de-canabidiol","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2021\/04\/22\/inpi-pode-anular-patente-de-remedio-a-base-de-canabidiol\/","title":{"rendered":"INPI PODE ANULAR PATENTE DE REM\u00c9DIO \u00c0 BASE DE CANABIDIOL"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Se houver decis\u00e3o definitiva pela derrubada da patente, a empresa ainda pode recorrer \u00e0 Justi\u00e7a.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A farmac\u00eautica paranaense Prati-Donaduzzi corre o risco de perder a patente de um medicamento \u00e0 base de canabidiol (CBD) dilu\u00eddo em \u00f3leo de milho, usado para controlar crises de ansiedade e epilepsia. Parecer t\u00e9cnico do Instituto Nacional da Propriedade Industrial (INPI), do dia 31 de mar\u00e7o, solicitou a anula\u00e7\u00e3o do direito, concedido em junho do ano passado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os t\u00e9cnicos do \u00f3rg\u00e3o entenderam que a subst\u00e2ncia n\u00e3o pode ser considerada atividade inventiva. O texto agora precisa ser aprovado pela dire\u00e7\u00e3o do INPI. A fabricante ainda teria 15 anos para explorar a patent<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O caso \u00e9 relevante porque abre a possibilidade de outras empresas do setor farmac\u00eautico produzirem produtos com CBD, j\u00e1 que atualmente os \u00f3leos da Prati-Donaduzzi s\u00e3o os \u00fanicos com autoriza\u00e7\u00e3o da Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) para venda em farm\u00e1cias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A farmac\u00eautica entrou com o pedido de patente em setembro de 2016. Com a decis\u00e3o, em junho de 2020, passou a ter 20 anos para explorar a patente, a contar de 2016 \u2014 ou seja, at\u00e9 setembro de 2036.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ap\u00f3s a concess\u00e3o da patente, o INPI recebeu tr\u00eas contesta\u00e7\u00f5es para anula\u00e7\u00e3o administrativa da decis\u00e3o. O primeiro pedido foi feito por Ant\u00f4nio Luiz Marchioni, o padre Tic\u00e3o, de S\u00e3o Paulo, que morreu em janeiro e era conhecido por ser defensor das causas sociais, e pelo deputado federal Paulo Teixeira (PT-SP), presidente da Comiss\u00e3o Especial sobre Medicamentos Formulados com Cannabis da C\u00e2mara dos Deputados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Outros dois pedidos foram encaminhados pela Herbarium Laborat\u00f3rio Bot\u00e2nico e por Leticia Provedel, s\u00f3cia do escrit\u00f3rio Souto Correa Advogados, que representa uma farmac\u00eautica israelense. Para Leticia, a decis\u00e3o do \u00f3rg\u00e3o representa uma reviravolta. \u201cPara ser patenteado, [produto] tem que ser novidade no mundo inteiro e j\u00e1 haviam estudos anteriores ao pedido\u201d, diz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Segundo o parecer do INPI, estudos publicados em 1993 e depois em 2015 j\u00e1 mencionavam um composto de CBD com \u00f3leo de milho. Por isso, afirmam t\u00e9cnicos do \u00f3rg\u00e3o, a patente n\u00e3o atenderia aos requisitos dispostos nos artigos 8\u00b0 e 13 da Lei de Propriedade Industrial (BR 112018005423-2 ).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cApenas alterar a concentra\u00e7\u00e3o de CBD e acrescentar excipientes, como antioxidantes, ado\u00e7ante, aromatizante e conservante, de modo a prover uma composi\u00e7\u00e3o oral l\u00edquida de CBD \u00e9 uma modifica\u00e7\u00e3o trivial que est\u00e1 dentro das habilidades ordin\u00e1rias de um t\u00e9cnico no assunto na \u00e1rea de tecnologia farmac\u00eautica\u201d, diz o documento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Com a publica\u00e7\u00e3o do parecer, a Prati-Donaduzzi tem prazo de 60 dias para se manifestar, at\u00e9 que o caso seja analisado pela dire\u00e7\u00e3o do INPI. \u201cAcho dif\u00edcil de reverter a decis\u00e3o porque o parecer j\u00e1 abordou a totalidade do contexto\u201d, diz Leticia Provedel.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O INPI n\u00e3o tem prazo para analisar a discuss\u00e3o, mas o tr\u00e2mite segue com prioridade, de acordo com a advogada, uma vez que foi o primeiro pedido depositado no Brasil. Se houver decis\u00e3o definitiva pela derrubada da patente, a empresa ainda pode recorrer \u00e0 Justi\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O mercado, diz a advogada, vem demonstrando interesse na comercializa\u00e7\u00e3o dos f\u00e1rmacos de canabidiol. \u201cNos Estados Unidos por exemplo, j\u00e1 existe uma ind\u00fastria fort\u00edssima\u201d, afirma. A Anvisa j\u00e1 regulamentou seu uso para fins medicinais e a importa\u00e7\u00e3o da mat\u00e9ria prima e diversas pessoas j\u00e1 obtiveram na Justi\u00e7a, por meio de habeas corpus, autoriza\u00e7\u00e3o para consumo medicinal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O agroneg\u00f3cio brasileiro, contudo, acrescenta, est\u00e1 ficando para tr\u00e1s, uma vez que o pa\u00eds n\u00e3o permite o cultivo de canabis para fins medicinais, o que j\u00e1 ocorre em diversos pa\u00edses como Uruguai, \u00c1frica do Sul, Canad\u00e1, Estados Unidos, Espanha e B\u00e9lgica. O tema est\u00e1 sendo discutido no Congresso em cerca de 20 projetos de lei que tratam da canabis no Brasil. Entre eles, o de n\u00ba 399, de 2015, que quer legalizar o cultivo para fins medicinais e industriais.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Procurada pelo Valor, Prati-Donaduzzi informou, por meio de sua assessoria de imprensa, que n\u00e3o conseguiria neste momento responder \u00e0 demanda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Valor Econ\u00f4mico &#8211; Por Adriana Aguiar, Valor \u2014 S\u00e3o Paulo<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se houver decis\u00e3o definitiva pela derrubada da patente, a empresa [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-4bM","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16106"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16106"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16106\/revisions"}],"predecessor-version":[{"id":16107,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16106\/revisions\/16107"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16106"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}