{"id":16104,"date":"2021-04-22T11:06:55","date_gmt":"2021-04-22T14:06:55","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=16104"},"modified":"2021-04-22T11:06:55","modified_gmt":"2021-04-22T14:06:55","slug":"menor-onerosidade-stj-admite-substituicao-de-penhora-de-dinheiro-que-e-alvo-de-cessao-fiduciaria","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2021\/04\/22\/menor-onerosidade-stj-admite-substituicao-de-penhora-de-dinheiro-que-e-alvo-de-cessao-fiduciaria\/","title":{"rendered":"MENOR ONEROSIDADE &#8211; STJ ADMITE SUBSTITUI\u00c7\u00c3O DE PENHORA DE DINHEIRO QUE \u00c9 ALVO DE CESS\u00c3O FIDUCI\u00c1RIA"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Penhora referente a execu\u00e7\u00e3o fiscal atingiu conta cujos valores s\u00e3o alvo de cess\u00e3o fiduci\u00e1ria de direito credit\u00f3rio.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Se o dinheiro bloqueado na conta corrente de um devedor como garantia da execu\u00e7\u00e3o fiscal est\u00e1 vinculado a cess\u00e3o fiduci\u00e1ria de direito credit\u00f3rio, \u00e9 poss\u00edvel substitui-lo por fian\u00e7a-banc\u00e1ria ou seguro-garantia, mesmo sem anu\u00eancia da Fazenda P\u00fablica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Com esse entendimento e por maioria de votos, a 2\u00aa Turma do Superior Tribunal de Justi\u00e7a manteve ac\u00f3rd\u00e3o do Tribunal de Justi\u00e7a do Paran\u00e1 que deferiu, contra os interessas da Fazenda P\u00fablica, a substitui\u00e7\u00e3o do bloqueio de valores depositados em conta por uma empresa alvo de execu\u00e7\u00e3o fiscal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Os valores penhorados est\u00e3o em conta vinculada a cess\u00e3o fiduci\u00e1ria de direito credit\u00f3rio feita a um banco do qual a empresa \u00e9 devedora. Ou seja, o dinheiro que cai nessa conta \u00e9 destinado a pagar a d\u00edvida com a institui\u00e7\u00e3o banc\u00e1ria.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Foi levando em considera\u00e7\u00e3o essa particularidade que o TJ-PR admitiu a substitui\u00e7\u00e3o, aplicando a jurisprud\u00eancia do pr\u00f3prio STJ. Os precedentes da corte indicam que a troca do dep\u00f3sito judicial em dinheiro por seguro-fian\u00e7a ou seguro-garantia pode ser feita em situa\u00e7\u00f5es excepcionais.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Tr\u00eas ministros da 2\u00aa Turma formaram maioria ao entender que a jurisprud\u00eancia foi bem aplicada ao caso pelo TJ-PR: Mauro Campbell, Og Fernandes e Assusete Magalh\u00e3es.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para eles, rever as conclus\u00f5es da corte estadual demandaria reexame de provas, o que \u00e9 vedado pela S\u00famula 7. Votaram ent\u00e3o por dar provimento ao agravo interno para n\u00e3o conhecer do recurso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ficaram vencidos o relator, ministro Herman Benjamin, e o ministro Francisco Falc\u00e3o. Para eles, n\u00e3o se admite a substitui\u00e7\u00e3o de dep\u00f3sito em dinheiro por outra garantia sem concord\u00e2ncia da Fazenda P\u00fablica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">&#8220;N\u00e3o consta, no ac\u00f3rd\u00e3o recorrido, motiva\u00e7\u00e3o pautada em elementos concretos que justifiquem, com base no princ\u00edpio da menor onerosidade, a exce\u00e7\u00e3o \u00e0 regra&#8221;, disse o ministro Herman Benjamin, que havia dado provimento ao recurso da Fazenda de maneira monocr\u00e1tica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">REsp 1.731.804<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Conjur &#8211; Por Danilo Vital<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Penhora referente a execu\u00e7\u00e3o fiscal atingiu conta cujos valores s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-4bK","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16104"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16104"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16104\/revisions"}],"predecessor-version":[{"id":16105,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16104\/revisions\/16105"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16104"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}