{"id":16094,"date":"2021-04-22T11:03:56","date_gmt":"2021-04-22T14:03:56","guid":{"rendered":"http:\/\/bonettiassociados.com.br\/?p=16094"},"modified":"2021-04-22T11:03:56","modified_gmt":"2021-04-22T14:03:56","slug":"simples-nacional-adotado-pix-para-facilitar-o-dia-a-dia-de-mais-de-16-milhoes-de-contribuintes","status":"publish","type":"post","link":"http:\/\/bonettiassociados.com.br\/index.php\/2021\/04\/22\/simples-nacional-adotado-pix-para-facilitar-o-dia-a-dia-de-mais-de-16-milhoes-de-contribuintes\/","title":{"rendered":"SIMPLES NACIONAL &#8211; ADOTADO PIX PARA FACILITAR O DIA A DIA DE MAIS DE 16 MILH\u00d5ES DE CONTRIBUINTES"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Serpro implementa melhorias no sistema para facilitar a quita\u00e7\u00e3o do Documento de Arrecada\u00e7\u00e3o do Simples Nacional pelo novo meio de pagamento eletr\u00f4nico.<\/span><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A partir desta quinta-feira, 22, os mais de 16 milh\u00f5es de contribuintes optantes pelo Simples Nacional j\u00e1 poder\u00e3o recolher os tributos abrangidos no Documento de Arrecada\u00e7\u00e3o do Simples Nacional (DAS) com o PIX, solu\u00e7\u00e3o de pagamento instant\u00e2neo criada pelo Banco Central. O Serpro, empresa de intelig\u00eancia em TI do governo federal, implementou melhorias tecnol\u00f3gicas no sistema de emiss\u00e3o do DAS do Portal do Simples Nacional para facilitar a quita\u00e7\u00e3o do tributo por meio de QR Code.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Simples Nacional \u00e9 um regime de tributa\u00e7\u00e3o especial da Receita Federal aplic\u00e1vel \u00e0s microempresas (ME), empresas de pequeno porte (EPP) e ao microempreendedor individual (MEI). &#8220;Hoje temos mais de 11 milh\u00f5es de MEI e mais de 5 milh\u00f5es de empresas cadastradas nesse regime de tributa\u00e7\u00e3o e que precisam quitar o DAS mensalmente e seguimos ampliando nossas a\u00e7\u00f5es para que o processo de cumprimento de obriga\u00e7\u00f5es pelos empregadores seja cada vez mais simples, mais \u00e1gil&#8221; explica, Andr\u00e9 de Cesero, diretor de Relacionamento com Clientes do Serpro. &#8220;No \u00e2mbito da Receita Federal j\u00e1 \u00e9 poss\u00edvel emitir o documento de arrecada\u00e7\u00e3o com QR Code de pagamento pelo PIX para eSocial dom\u00e9stico (DAE), alguns DARF e agora ser\u00e1 poss\u00edvel para todo Simples Nacional (DAS)&#8221;, completa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A possibilidade de quita\u00e7\u00e3o por meio do QR Code do PIX tamb\u00e9m contemplar\u00e1 os DAS emitidos para os contribuintes que tiveram seus pedidos de parcelamento deferidos, facilitando o pagamento a qualquer hora e qualquer dia da semana e em qualquer banco que ofere\u00e7a esta op\u00e7\u00e3o de pagamento, independente de ser ou n\u00e3o um banco habilitado para recebimento de DAS. A emiss\u00e3o da guia \u00e9 feita do mesmo jeito. N\u00e3o houve altera\u00e7\u00e3o no procedimento para o contribuinte.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Como pagar a guia DAS usando o PIX<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Documento de Arrecada\u00e7\u00e3o do Simples Nacional (DAS) deve ser emitido pelo empregador diretamente no Portal do Simples Nacional ou pelo app MEI , vers\u00f5es iOS (App Store) e Android (Google Play), destinado ao Microempreendedor Individual.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ao emitir o documento, ser\u00e1 gerado tamb\u00e9m um QR Code, automaticamente, na guia de pagamento. Com o QR Code, o empregador pode efetuar o pagamento, n\u00e3o sendo necess\u00e1ria nenhuma outra a\u00e7\u00e3o adicional por parte do usu\u00e1rio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O que \u00e9 o Simples Nacional?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Simples Nacional \u00e9 o nome abreviado do &#8220;Regime Especial Unificado de Arrecada\u00e7\u00e3o de Tributos e Contribui\u00e7\u00f5es devidos pelas Microempresas e Empresas de Pequeno Porte&#8221;. Trata-se de um regime compartilhado de arrecada\u00e7\u00e3o, cobran\u00e7a e fiscaliza\u00e7\u00e3o de tributos aplic\u00e1vel \u00e0s Microempresas e Empresas de Pequeno Porte, previsto na Lei Complementar n\u00ba 123 , de 14 de dezembro de 2006, al\u00e9m de Microempreendedor Individual.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Abrange a participa\u00e7\u00e3o de todos os entes federados (Uni\u00e3o, Estados, Distrito Federal e Munic\u00edpios) e unifica o pagamento de diversos tributos tais como Imposto sobre a Renda da Pessoa Jur\u00eddica (IRPJ), Imposto sobre Produtos Industrializados (IPI), Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social (Cofins), Imposto sobre Opera\u00e7\u00f5es Relativas \u00e0 Circula\u00e7\u00e3o de Mercadorias e Sobre Presta\u00e7\u00f5es de Servi\u00e7os de Transporte Interestadual e Intermunicipal e de Comunica\u00e7\u00e3o (ICMS) e Imposto sobre Servi\u00e7os de Qualquer Natureza (ISS).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FONTE: Serpro<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Serpro implementa melhorias no sistema para facilitar a quita\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paFpWR-4bA","_links":{"self":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16094"}],"collection":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16094"}],"version-history":[{"count":1,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16094\/revisions"}],"predecessor-version":[{"id":16095,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16094\/revisions\/16095"}],"wp:attachment":[{"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16094"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bonettiassociados.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}